{"id":28852,"date":"2025-10-22T11:36:37","date_gmt":"2025-10-22T14:36:37","guid":{"rendered":"https:\/\/diariodepe.com.br\/xinhua\/?p=28852"},"modified":"2025-10-22T13:42:52","modified_gmt":"2025-10-22T16:42:52","slug":"empresas-estao-otimistas-quanto-as-perspectivas-de-negocios-na-gba-segundo-indice","status":"publish","type":"post","link":"https:\/\/diariodepe.com.br\/xinhua\/2025\/10\/22\/empresas-estao-otimistas-quanto-as-perspectivas-de-negocios-na-gba-segundo-indice\/","title":{"rendered":"Empresas est\u00e3o otimistas quanto \u00e0s perspectivas de neg\u00f3cios na GBA, segundo \u00edndice"},"content":{"rendered":"<p>Hong Kong &#8211; Empresas que operam na Grande \u00c1rea da Ba\u00eda Guangdong-Hong Kong-Macau (GBA, em ingl\u00eas) em setores-chave est\u00e3o otimistas com as perspectivas de neg\u00f3cios em 2026, sendo que as expectativas mais elevadas foram observadas no setor de inova\u00e7\u00e3o cient\u00edfica e tecnol\u00f3gica, de acordo com o \u00cdndice de Desenvolvimento Industrial da Grande \u00c1rea da Ba\u00eda 2025, divulgado nesta ter\u00e7a-feira.<\/p>\n<p>O \u00cdndice, apresentado em conjunto pela Our Hong Kong Foundation e pelo Dah Sing Bank, acompanha o desempenho de 11 cidades em seis setores-chave &#8212; servi\u00e7os financeiros, inova\u00e7\u00e3o e tecnologia, com\u00e9rcio e log\u00edstica, manufatura, constru\u00e7\u00e3o e imobili\u00e1rio, bem como cultura, esportes e turismo.<\/p>\n<p>Calculado com base em pesquisas com mais de 3.400 empresas da GBA, o sub\u00edndice de confian\u00e7a obteve 55,5 para 2025 e 57,3 para 2026, o que sinalizou um aquecimento do sentimento do mercado ao longo do pr\u00f3ximo ano.<\/p>\n<p>At\u00e9 agora, neste ano, a taxa de crescimento anualizada geral dos seis setores-chave da GBA subiu de 4,9% no ano anterior para 7,1%, liderada pelo setor de inova\u00e7\u00e3o e tecnologia, com uma expans\u00e3o robusta de 14,8%. A manufatura cresceu 8,1% ano a ano, \u00e0 medida que se move em dire\u00e7\u00e3o \u00e0 automa\u00e7\u00e3o inteligente.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hong Kong &#8211; Empresas que operam na Grande \u00c1rea da Ba\u00eda Guangdong-Hong Kong-Macau (GBA, em ingl\u00eas) em setores-chave est\u00e3o otimistas com as perspectivas de neg\u00f3cios em 2026, sendo que as expectativas mais elevadas foram observadas no setor de inova\u00e7\u00e3o cient\u00edfica&#8230;<\/p>\n","protected":false},"author":7,"featured_media":28853,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-28852","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-china"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Empresas est\u00e3o otimistas quanto \u00e0s perspectivas de neg\u00f3cios na GBA, segundo \u00edndice - Xinhua - Diario de Pernambuco<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/diariodepe.com.br\/xinhua\/2025\/10\/22\/empresas-estao-otimistas-quanto-as-perspectivas-de-negocios-na-gba-segundo-indice\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Empresas est\u00e3o otimistas quanto \u00e0s perspectivas de neg\u00f3cios na GBA, segundo \u00edndice - Xinhua - Diario de Pernambuco\" \/>\n<meta property=\"og:description\" content=\"Hong Kong &#8211; Empresas que operam na Grande \u00c1rea da Ba\u00eda Guangdong-Hong Kong-Macau (GBA, em ingl\u00eas) em setores-chave est\u00e3o otimistas com as perspectivas de neg\u00f3cios em 2026, sendo que as expectativas mais elevadas foram observadas no setor de inova\u00e7\u00e3o cient\u00edfica...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/diariodepe.com.br\/xinhua\/2025\/10\/22\/empresas-estao-otimistas-quanto-as-perspectivas-de-negocios-na-gba-segundo-indice\/\" \/>\n<meta property=\"og:site_name\" content=\"Xinhua - Diario de Pernambuco\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-22T14:36:37+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-22T16:42:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/diariodepe.com.br\/xinhua\/wp-content\/uploads\/sites\/3\/2025\/10\/202510220f4346089d55407f8dc1d6c400c6c7cd_XxjwspP000010_20251022_CBMFN0A001.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"617\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ag\u00eancia Xinhua\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ag\u00eancia Xinhua\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/diariodepe.com.br\\\/xinhua\\\/2025\\\/10\\\/22\\\/empresas-estao-otimistas-quanto-as-perspectivas-de-negocios-na-gba-segundo-indice\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diariodepe.com.br\\\/xinhua\\\/2025\\\/10\\\/22\\\/empresas-estao-otimistas-quanto-as-perspectivas-de-negocios-na-gba-segundo-indice\\\/\"},\"author\":{\"name\":\"Ag\u00eancia Xinhua\",\"@id\":\"https:\\\/\\\/diariodepe.com.br\\\/xinhua\\\/#\\\/schema\\\/person\\\/fee9050ea7ed36c8dee0b3d997f13743\"},\"headline\":\"Empresas est\u00e3o otimistas quanto \u00e0s perspectivas de neg\u00f3cios na GBA, segundo \u00edndice\",\"datePublished\":\"2025-10-22T14:36:37+00:00\",\"dateModified\":\"2025-10-22T16:42:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/diariodepe.com.br\\\/xinhua\\\/2025\\\/10\\\/22\\\/empresas-estao-otimistas-quanto-as-perspectivas-de-negocios-na-gba-segundo-indice\\\/\"},\"wordCount\":215,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/diariodepe.com.br\\\/xinhua\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/diariodepe.com.br\\\/xinhua\\\/2025\\\/10\\\/22\\\/empresas-estao-otimistas-quanto-as-perspectivas-de-negocios-na-gba-segundo-indice\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/diariodepe.com.br\\\/xinhua\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2025\\\/10\\\/202510220f4346089d55407f8dc1d6c400c6c7cd_XxjwspP000010_20251022_CBMFN0A001.jpeg\",\"articleSection\":[\"China\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/diariodepe.com.br\\\/xinhua\\\/2025\\\/10\\\/22\\\/empresas-estao-otimistas-quanto-as-perspectivas-de-negocios-na-gba-segundo-indice\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/diariodepe.com.br\\\/xinhua\\\/2025\\\/10\\\/22\\\/empresas-estao-otimistas-quanto-as-perspectivas-de-negocios-na-gba-segundo-indice\\\/\",\"url\":\"https:\\\/\\\/diariodepe.com.br\\\/xinhua\\\/2025\\\/10\\\/22\\\/empresas-estao-otimistas-quanto-as-perspectivas-de-negocios-na-gba-segundo-indice\\\/\",\"name\":\"Empresas est\u00e3o otimistas quanto \u00e0s perspectivas de neg\u00f3cios na GBA, segundo \u00edndice - Xinhua - Diario de Pernambuco\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diariodepe.com.br\\\/xinhua\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/diariodepe.com.br\\\/xinhua\\\/2025\\\/10\\\/22\\\/empresas-estao-otimistas-quanto-as-perspectivas-de-negocios-na-gba-segundo-indice\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/diariodepe.com.br\\\/xinhua\\\/2025\\\/10\\\/22\\\/empresas-estao-otimistas-quanto-as-perspectivas-de-negocios-na-gba-segundo-indice\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/diariodepe.com.br\\\/xinhua\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2025\\\/10\\\/202510220f4346089d55407f8dc1d6c400c6c7cd_XxjwspP000010_20251022_CBMFN0A001.jpeg\",\"datePublished\":\"2025-10-22T14:36:37+00:00\",\"dateModified\":\"2025-10-22T16:42:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/diariodepe.com.br\\\/xinhua\\\/2025\\\/10\\\/22\\\/empresas-estao-otimistas-quanto-as-perspectivas-de-negocios-na-gba-segundo-indice\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/diariodepe.com.br\\\/xinhua\\\/2025\\\/10\\\/22\\\/empresas-estao-otimistas-quanto-as-perspectivas-de-negocios-na-gba-segundo-indice\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/diariodepe.com.br\\\/xinhua\\\/2025\\\/10\\\/22\\\/empresas-estao-otimistas-quanto-as-perspectivas-de-negocios-na-gba-segundo-indice\\\/#primaryimage\",\"url\":\"https:\\\/\\\/diariodepe.com.br\\\/xinhua\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2025\\\/10\\\/202510220f4346089d55407f8dc1d6c400c6c7cd_XxjwspP000010_20251022_CBMFN0A001.jpeg\",\"contentUrl\":\"https:\\\/\\\/diariodepe.com.br\\\/xinhua\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2025\\\/10\\\/202510220f4346089d55407f8dc1d6c400c6c7cd_XxjwspP000010_20251022_CBMFN0A001.jpeg\",\"width\":900,\"height\":617,\"caption\":\"(251001) -- HONG KONG, Oct. 1, 2025 (Xinhua) -- Fireworks celebrating the 76th anniversary of the founding of the People's Republic of China illuminate the sky over Victoria Harbour in Hong Kong, south China, Oct. 1, 2025. (Xinhua\\\/Chen Duo)\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/diariodepe.com.br\\\/xinhua\\\/2025\\\/10\\\/22\\\/empresas-estao-otimistas-quanto-as-perspectivas-de-negocios-na-gba-segundo-indice\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/diariodepe.com.br\\\/xinhua\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Empresas est\u00e3o otimistas quanto \u00e0s perspectivas de neg\u00f3cios na GBA, segundo \u00edndice\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/diariodepe.com.br\\\/xinhua\\\/#website\",\"url\":\"https:\\\/\\\/diariodepe.com.br\\\/xinhua\\\/\",\"name\":\"Xinhua - Diario de Pernambuco\",\"description\":\"A maior ag\u00eancia de not\u00edcias da China e um dos principais canais para conhecer o pa\u00eds\",\"publisher\":{\"@id\":\"https:\\\/\\\/diariodepe.com.br\\\/xinhua\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/diariodepe.com.br\\\/xinhua\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/diariodepe.com.br\\\/xinhua\\\/#organization\",\"name\":\"Xinhua - Diario de Pernambuco\",\"url\":\"https:\\\/\\\/diariodepe.com.br\\\/xinhua\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/diariodepe.com.br\\\/xinhua\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/diariodepe.com.br\\\/xinhua\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2020\\\/10\\\/cropped-logo-transparente-2.png\",\"contentUrl\":\"https:\\\/\\\/diariodepe.com.br\\\/xinhua\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2020\\\/10\\\/cropped-logo-transparente-2.png\",\"width\":512,\"height\":164,\"caption\":\"Xinhua - Diario de Pernambuco\"},\"image\":{\"@id\":\"https:\\\/\\\/diariodepe.com.br\\\/xinhua\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/diariodepe.com.br\\\/xinhua\\\/#\\\/schema\\\/person\\\/fee9050ea7ed36c8dee0b3d997f13743\",\"name\":\"Ag\u00eancia Xinhua\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a406bf2cbb7318a49853cafe127e069e225f65f8de88227ada34c65a51813e14?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a406bf2cbb7318a49853cafe127e069e225f65f8de88227ada34c65a51813e14?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a406bf2cbb7318a49853cafe127e069e225f65f8de88227ada34c65a51813e14?s=96&d=mm&r=g\",\"caption\":\"Ag\u00eancia Xinhua\"},\"sameAs\":[\"https:\\\/\\\/www.diariodepernambuco.com.br\"],\"url\":\"https:\\\/\\\/diariodepe.com.br\\\/xinhua\\\/author\\\/agencia-xinhua\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Empresas est\u00e3o otimistas quanto \u00e0s perspectivas de neg\u00f3cios na GBA, segundo \u00edndice - Xinhua - Diario de Pernambuco","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/diariodepe.com.br\/xinhua\/2025\/10\/22\/empresas-estao-otimistas-quanto-as-perspectivas-de-negocios-na-gba-segundo-indice\/","og_locale":"pt_BR","og_type":"article","og_title":"Empresas est\u00e3o otimistas quanto \u00e0s perspectivas de neg\u00f3cios na GBA, segundo \u00edndice - Xinhua - Diario de Pernambuco","og_description":"Hong Kong &#8211; Empresas que operam na Grande \u00c1rea da Ba\u00eda Guangdong-Hong Kong-Macau (GBA, em ingl\u00eas) em setores-chave est\u00e3o otimistas com as perspectivas de neg\u00f3cios em 2026, sendo que as expectativas mais elevadas foram observadas no setor de inova\u00e7\u00e3o cient\u00edfica...","og_url":"https:\/\/diariodepe.com.br\/xinhua\/2025\/10\/22\/empresas-estao-otimistas-quanto-as-perspectivas-de-negocios-na-gba-segundo-indice\/","og_site_name":"Xinhua - Diario de Pernambuco","article_published_time":"2025-10-22T14:36:37+00:00","article_modified_time":"2025-10-22T16:42:52+00:00","og_image":[{"width":900,"height":617,"url":"https:\/\/diariodepe.com.br\/xinhua\/wp-content\/uploads\/sites\/3\/2025\/10\/202510220f4346089d55407f8dc1d6c400c6c7cd_XxjwspP000010_20251022_CBMFN0A001.jpeg","type":"image\/jpeg"}],"author":"Ag\u00eancia Xinhua","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Ag\u00eancia Xinhua","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/diariodepe.com.br\/xinhua\/2025\/10\/22\/empresas-estao-otimistas-quanto-as-perspectivas-de-negocios-na-gba-segundo-indice\/#article","isPartOf":{"@id":"https:\/\/diariodepe.com.br\/xinhua\/2025\/10\/22\/empresas-estao-otimistas-quanto-as-perspectivas-de-negocios-na-gba-segundo-indice\/"},"author":{"name":"Ag\u00eancia Xinhua","@id":"https:\/\/diariodepe.com.br\/xinhua\/#\/schema\/person\/fee9050ea7ed36c8dee0b3d997f13743"},"headline":"Empresas est\u00e3o otimistas quanto \u00e0s perspectivas de neg\u00f3cios na GBA, segundo \u00edndice","datePublished":"2025-10-22T14:36:37+00:00","dateModified":"2025-10-22T16:42:52+00:00","mainEntityOfPage":{"@id":"https:\/\/diariodepe.com.br\/xinhua\/2025\/10\/22\/empresas-estao-otimistas-quanto-as-perspectivas-de-negocios-na-gba-segundo-indice\/"},"wordCount":215,"commentCount":0,"publisher":{"@id":"https:\/\/diariodepe.com.br\/xinhua\/#organization"},"image":{"@id":"https:\/\/diariodepe.com.br\/xinhua\/2025\/10\/22\/empresas-estao-otimistas-quanto-as-perspectivas-de-negocios-na-gba-segundo-indice\/#primaryimage"},"thumbnailUrl":"https:\/\/diariodepe.com.br\/xinhua\/wp-content\/uploads\/sites\/3\/2025\/10\/202510220f4346089d55407f8dc1d6c400c6c7cd_XxjwspP000010_20251022_CBMFN0A001.jpeg","articleSection":["China"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/diariodepe.com.br\/xinhua\/2025\/10\/22\/empresas-estao-otimistas-quanto-as-perspectivas-de-negocios-na-gba-segundo-indice\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/diariodepe.com.br\/xinhua\/2025\/10\/22\/empresas-estao-otimistas-quanto-as-perspectivas-de-negocios-na-gba-segundo-indice\/","url":"https:\/\/diariodepe.com.br\/xinhua\/2025\/10\/22\/empresas-estao-otimistas-quanto-as-perspectivas-de-negocios-na-gba-segundo-indice\/","name":"Empresas est\u00e3o otimistas quanto \u00e0s perspectivas de neg\u00f3cios na GBA, segundo \u00edndice - Xinhua - Diario de Pernambuco","isPartOf":{"@id":"https:\/\/diariodepe.com.br\/xinhua\/#website"},"primaryImageOfPage":{"@id":"https:\/\/diariodepe.com.br\/xinhua\/2025\/10\/22\/empresas-estao-otimistas-quanto-as-perspectivas-de-negocios-na-gba-segundo-indice\/#primaryimage"},"image":{"@id":"https:\/\/diariodepe.com.br\/xinhua\/2025\/10\/22\/empresas-estao-otimistas-quanto-as-perspectivas-de-negocios-na-gba-segundo-indice\/#primaryimage"},"thumbnailUrl":"https:\/\/diariodepe.com.br\/xinhua\/wp-content\/uploads\/sites\/3\/2025\/10\/202510220f4346089d55407f8dc1d6c400c6c7cd_XxjwspP000010_20251022_CBMFN0A001.jpeg","datePublished":"2025-10-22T14:36:37+00:00","dateModified":"2025-10-22T16:42:52+00:00","breadcrumb":{"@id":"https:\/\/diariodepe.com.br\/xinhua\/2025\/10\/22\/empresas-estao-otimistas-quanto-as-perspectivas-de-negocios-na-gba-segundo-indice\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/diariodepe.com.br\/xinhua\/2025\/10\/22\/empresas-estao-otimistas-quanto-as-perspectivas-de-negocios-na-gba-segundo-indice\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/diariodepe.com.br\/xinhua\/2025\/10\/22\/empresas-estao-otimistas-quanto-as-perspectivas-de-negocios-na-gba-segundo-indice\/#primaryimage","url":"https:\/\/diariodepe.com.br\/xinhua\/wp-content\/uploads\/sites\/3\/2025\/10\/202510220f4346089d55407f8dc1d6c400c6c7cd_XxjwspP000010_20251022_CBMFN0A001.jpeg","contentUrl":"https:\/\/diariodepe.com.br\/xinhua\/wp-content\/uploads\/sites\/3\/2025\/10\/202510220f4346089d55407f8dc1d6c400c6c7cd_XxjwspP000010_20251022_CBMFN0A001.jpeg","width":900,"height":617,"caption":"(251001) -- HONG KONG, Oct. 1, 2025 (Xinhua) -- Fireworks celebrating the 76th anniversary of the founding of the People's Republic of China illuminate the sky over Victoria Harbour in Hong Kong, south China, Oct. 1, 2025. (Xinhua\/Chen Duo)"},{"@type":"BreadcrumbList","@id":"https:\/\/diariodepe.com.br\/xinhua\/2025\/10\/22\/empresas-estao-otimistas-quanto-as-perspectivas-de-negocios-na-gba-segundo-indice\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/diariodepe.com.br\/xinhua\/"},{"@type":"ListItem","position":2,"name":"Empresas est\u00e3o otimistas quanto \u00e0s perspectivas de neg\u00f3cios na GBA, segundo \u00edndice"}]},{"@type":"WebSite","@id":"https:\/\/diariodepe.com.br\/xinhua\/#website","url":"https:\/\/diariodepe.com.br\/xinhua\/","name":"Xinhua - Diario de Pernambuco","description":"A maior ag\u00eancia de not\u00edcias da China e um dos principais canais para conhecer o pa\u00eds","publisher":{"@id":"https:\/\/diariodepe.com.br\/xinhua\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/diariodepe.com.br\/xinhua\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/diariodepe.com.br\/xinhua\/#organization","name":"Xinhua - Diario de Pernambuco","url":"https:\/\/diariodepe.com.br\/xinhua\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/diariodepe.com.br\/xinhua\/#\/schema\/logo\/image\/","url":"https:\/\/diariodepe.com.br\/xinhua\/wp-content\/uploads\/sites\/3\/2020\/10\/cropped-logo-transparente-2.png","contentUrl":"https:\/\/diariodepe.com.br\/xinhua\/wp-content\/uploads\/sites\/3\/2020\/10\/cropped-logo-transparente-2.png","width":512,"height":164,"caption":"Xinhua - Diario de Pernambuco"},"image":{"@id":"https:\/\/diariodepe.com.br\/xinhua\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/diariodepe.com.br\/xinhua\/#\/schema\/person\/fee9050ea7ed36c8dee0b3d997f13743","name":"Ag\u00eancia Xinhua","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/a406bf2cbb7318a49853cafe127e069e225f65f8de88227ada34c65a51813e14?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a406bf2cbb7318a49853cafe127e069e225f65f8de88227ada34c65a51813e14?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a406bf2cbb7318a49853cafe127e069e225f65f8de88227ada34c65a51813e14?s=96&d=mm&r=g","caption":"Ag\u00eancia Xinhua"},"sameAs":["https:\/\/www.diariodepernambuco.com.br"],"url":"https:\/\/diariodepe.com.br\/xinhua\/author\/agencia-xinhua\/"}]}},"cc_featured_image_caption":{"caption_text":"","source_text":"","source_url":""},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/diariodepe.com.br\/xinhua\/wp-json\/wp\/v2\/posts\/28852","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diariodepe.com.br\/xinhua\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diariodepe.com.br\/xinhua\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diariodepe.com.br\/xinhua\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/diariodepe.com.br\/xinhua\/wp-json\/wp\/v2\/comments?post=28852"}],"version-history":[{"count":1,"href":"https:\/\/diariodepe.com.br\/xinhua\/wp-json\/wp\/v2\/posts\/28852\/revisions"}],"predecessor-version":[{"id":28854,"href":"https:\/\/diariodepe.com.br\/xinhua\/wp-json\/wp\/v2\/posts\/28852\/revisions\/28854"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diariodepe.com.br\/xinhua\/wp-json\/wp\/v2\/media\/28853"}],"wp:attachment":[{"href":"https:\/\/diariodepe.com.br\/xinhua\/wp-json\/wp\/v2\/media?parent=28852"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diariodepe.com.br\/xinhua\/wp-json\/wp\/v2\/categories?post=28852"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diariodepe.com.br\/xinhua\/wp-json\/wp\/v2\/tags?post=28852"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}