{"id":24080,"date":"2024-11-26T17:21:00","date_gmt":"2024-11-26T20:21:00","guid":{"rendered":"https:\/\/www.diariodepe.com.br\/xinhua\/?p=24080"},"modified":"2024-11-26T08:28:07","modified_gmt":"2024-11-26T11:28:07","slug":"livro-publicado-de-discursos-de-xi-sobre-governanca-das-forcas-armadas-baseadas-na-lei","status":"publish","type":"post","link":"https:\/\/diariodepe.com.br\/xinhua\/2024\/11\/26\/livro-publicado-de-discursos-de-xi-sobre-governanca-das-forcas-armadas-baseadas-na-lei\/","title":{"rendered":"Livro publicado de discursos de Xi sobre governan\u00e7a das for\u00e7as armadas baseadas na lei"},"content":{"rendered":"\n<p>Pequim &#8211; Foi publicada uma compila\u00e7\u00e3o de discursos de Xi Jinping, presidente da Comiss\u00e3o Militar Central (CMC), sobre governar as for\u00e7as armadas de acordo com a lei, de acordo com um comunicado oficial divulgado no domingo.<\/p>\n\n\n\n<p>Os discursos foram extra\u00eddos de discursos e trabalhos escritos de Xi entre novembro de 2012 e junho de 2024.<\/p>\n\n\n\n<p>A CMC instou os oficiais e soldados militares de todos os n\u00edveis a estudar completamente o livro e concebido especialmente para que os oficiais superiores desempenhem um papel exemplar no respeito, aprendizagem, observa\u00e7\u00e3o e aplica\u00e7\u00e3o das leis.<\/p>\n\n\n\n<p>Atrav\u00e9s do estudo do livro, os oficiais e soldados militares s\u00e3o obrigados a melhorar a sua capacidade de pensar e agir de acordo com o estado de direito no seu trabalho, acelerando assim as transforma\u00e7\u00f5es fundamentais na governan\u00e7a militar e fortalecendo o papel do estado de direito no seu trabalho. aprimoramento da defesa nacional e das capacidades militares.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pequim &#8211; Foi publicada uma compila\u00e7\u00e3o de discursos de Xi Jinping, presidente da Comiss\u00e3o Militar Central (CMC), sobre governar as for\u00e7as armadas de acordo com a lei, de acordo com um comunicado oficial divulgado no domingo. Os discursos foram extra\u00eddos&#8230;<\/p>\n","protected":false},"author":3,"featured_media":21056,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-24080","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-china"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Livro publicado de discursos de Xi sobre governan\u00e7a das for\u00e7as armadas baseadas na lei - Xinhua - Diario de Pernambuco<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/diariodepe.com.br\/xinhua\/2024\/11\/26\/livro-publicado-de-discursos-de-xi-sobre-governanca-das-forcas-armadas-baseadas-na-lei\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Livro publicado de discursos de Xi sobre governan\u00e7a das for\u00e7as armadas baseadas na lei - Xinhua - Diario de Pernambuco\" \/>\n<meta property=\"og:description\" content=\"Pequim &#8211; Foi publicada uma compila\u00e7\u00e3o de discursos de Xi Jinping, presidente da Comiss\u00e3o Militar Central (CMC), sobre governar as for\u00e7as armadas de acordo com a lei, de acordo com um comunicado oficial divulgado no domingo. Os discursos foram extra\u00eddos...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/diariodepe.com.br\/xinhua\/2024\/11\/26\/livro-publicado-de-discursos-de-xi-sobre-governanca-das-forcas-armadas-baseadas-na-lei\/\" \/>\n<meta property=\"og:site_name\" content=\"Xinhua - Diario de Pernambuco\" \/>\n<meta property=\"article:published_time\" content=\"2024-11-26T20:21:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/diariodepe.com.br\/xinhua\/wp-content\/uploads\/sites\/3\/2024\/07\/3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"388\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Marcelo Oliveira de A. Maranhao\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Marcelo Oliveira de A. Maranhao\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/diariodepe.com.br\\\/xinhua\\\/2024\\\/11\\\/26\\\/livro-publicado-de-discursos-de-xi-sobre-governanca-das-forcas-armadas-baseadas-na-lei\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diariodepe.com.br\\\/xinhua\\\/2024\\\/11\\\/26\\\/livro-publicado-de-discursos-de-xi-sobre-governanca-das-forcas-armadas-baseadas-na-lei\\\/\"},\"author\":{\"name\":\"Marcelo Oliveira de A. Maranhao\",\"@id\":\"https:\\\/\\\/diariodepe.com.br\\\/xinhua\\\/#\\\/schema\\\/person\\\/0943d6fd02bdc7b49c8f495e8787a2cb\"},\"headline\":\"Livro publicado de discursos de Xi sobre governan\u00e7a das for\u00e7as armadas baseadas na lei\",\"datePublished\":\"2024-11-26T20:21:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/diariodepe.com.br\\\/xinhua\\\/2024\\\/11\\\/26\\\/livro-publicado-de-discursos-de-xi-sobre-governanca-das-forcas-armadas-baseadas-na-lei\\\/\"},\"wordCount\":175,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/diariodepe.com.br\\\/xinhua\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/diariodepe.com.br\\\/xinhua\\\/2024\\\/11\\\/26\\\/livro-publicado-de-discursos-de-xi-sobre-governanca-das-forcas-armadas-baseadas-na-lei\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/diariodepe.com.br\\\/xinhua\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2024\\\/07\\\/3.jpg\",\"articleSection\":[\"China\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/diariodepe.com.br\\\/xinhua\\\/2024\\\/11\\\/26\\\/livro-publicado-de-discursos-de-xi-sobre-governanca-das-forcas-armadas-baseadas-na-lei\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/diariodepe.com.br\\\/xinhua\\\/2024\\\/11\\\/26\\\/livro-publicado-de-discursos-de-xi-sobre-governanca-das-forcas-armadas-baseadas-na-lei\\\/\",\"url\":\"https:\\\/\\\/diariodepe.com.br\\\/xinhua\\\/2024\\\/11\\\/26\\\/livro-publicado-de-discursos-de-xi-sobre-governanca-das-forcas-armadas-baseadas-na-lei\\\/\",\"name\":\"Livro publicado de discursos de Xi sobre governan\u00e7a das for\u00e7as armadas baseadas na lei - Xinhua - Diario de Pernambuco\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diariodepe.com.br\\\/xinhua\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/diariodepe.com.br\\\/xinhua\\\/2024\\\/11\\\/26\\\/livro-publicado-de-discursos-de-xi-sobre-governanca-das-forcas-armadas-baseadas-na-lei\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/diariodepe.com.br\\\/xinhua\\\/2024\\\/11\\\/26\\\/livro-publicado-de-discursos-de-xi-sobre-governanca-das-forcas-armadas-baseadas-na-lei\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/diariodepe.com.br\\\/xinhua\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2024\\\/07\\\/3.jpg\",\"datePublished\":\"2024-11-26T20:21:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/diariodepe.com.br\\\/xinhua\\\/2024\\\/11\\\/26\\\/livro-publicado-de-discursos-de-xi-sobre-governanca-das-forcas-armadas-baseadas-na-lei\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/diariodepe.com.br\\\/xinhua\\\/2024\\\/11\\\/26\\\/livro-publicado-de-discursos-de-xi-sobre-governanca-das-forcas-armadas-baseadas-na-lei\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/diariodepe.com.br\\\/xinhua\\\/2024\\\/11\\\/26\\\/livro-publicado-de-discursos-de-xi-sobre-governanca-das-forcas-armadas-baseadas-na-lei\\\/#primaryimage\",\"url\":\"https:\\\/\\\/diariodepe.com.br\\\/xinhua\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2024\\\/07\\\/3.jpg\",\"contentUrl\":\"https:\\\/\\\/diariodepe.com.br\\\/xinhua\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2024\\\/07\\\/3.jpg\",\"width\":388,\"height\":500,\"caption\":\"(130907) -- ASTANA, Sept. 7, 2013 (Xinhua) -- Chinese President Xi Jinping delivers a speech at the Nazarbayev University in Astana, Kazakhstan, Sept. 7, 2013. (Xinhua\\\/Wang Ye) (wqq)\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/diariodepe.com.br\\\/xinhua\\\/2024\\\/11\\\/26\\\/livro-publicado-de-discursos-de-xi-sobre-governanca-das-forcas-armadas-baseadas-na-lei\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/diariodepe.com.br\\\/xinhua\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Livro publicado de discursos de Xi sobre governan\u00e7a das for\u00e7as armadas baseadas na lei\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/diariodepe.com.br\\\/xinhua\\\/#website\",\"url\":\"https:\\\/\\\/diariodepe.com.br\\\/xinhua\\\/\",\"name\":\"Xinhua - Diario de Pernambuco\",\"description\":\"A maior ag\u00eancia de not\u00edcias da China e um dos principais canais para conhecer o pa\u00eds\",\"publisher\":{\"@id\":\"https:\\\/\\\/diariodepe.com.br\\\/xinhua\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/diariodepe.com.br\\\/xinhua\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/diariodepe.com.br\\\/xinhua\\\/#organization\",\"name\":\"Xinhua - Diario de Pernambuco\",\"url\":\"https:\\\/\\\/diariodepe.com.br\\\/xinhua\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/diariodepe.com.br\\\/xinhua\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/diariodepe.com.br\\\/xinhua\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2020\\\/10\\\/cropped-logo-transparente-2.png\",\"contentUrl\":\"https:\\\/\\\/diariodepe.com.br\\\/xinhua\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2020\\\/10\\\/cropped-logo-transparente-2.png\",\"width\":512,\"height\":164,\"caption\":\"Xinhua - Diario de Pernambuco\"},\"image\":{\"@id\":\"https:\\\/\\\/diariodepe.com.br\\\/xinhua\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/diariodepe.com.br\\\/xinhua\\\/#\\\/schema\\\/person\\\/0943d6fd02bdc7b49c8f495e8787a2cb\",\"name\":\"Marcelo Oliveira de A. Maranhao\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f562caee940d39879c20e90eea3e4b21860c7d4c96684c23141c554824f0059c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f562caee940d39879c20e90eea3e4b21860c7d4c96684c23141c554824f0059c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f562caee940d39879c20e90eea3e4b21860c7d4c96684c23141c554824f0059c?s=96&d=mm&r=g\",\"caption\":\"Marcelo Oliveira de A. Maranhao\"},\"url\":\"https:\\\/\\\/diariodepe.com.br\\\/xinhua\\\/author\\\/marcelo-maranhao\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Livro publicado de discursos de Xi sobre governan\u00e7a das for\u00e7as armadas baseadas na lei - Xinhua - Diario de Pernambuco","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/diariodepe.com.br\/xinhua\/2024\/11\/26\/livro-publicado-de-discursos-de-xi-sobre-governanca-das-forcas-armadas-baseadas-na-lei\/","og_locale":"pt_BR","og_type":"article","og_title":"Livro publicado de discursos de Xi sobre governan\u00e7a das for\u00e7as armadas baseadas na lei - Xinhua - Diario de Pernambuco","og_description":"Pequim &#8211; Foi publicada uma compila\u00e7\u00e3o de discursos de Xi Jinping, presidente da Comiss\u00e3o Militar Central (CMC), sobre governar as for\u00e7as armadas de acordo com a lei, de acordo com um comunicado oficial divulgado no domingo. Os discursos foram extra\u00eddos...","og_url":"https:\/\/diariodepe.com.br\/xinhua\/2024\/11\/26\/livro-publicado-de-discursos-de-xi-sobre-governanca-das-forcas-armadas-baseadas-na-lei\/","og_site_name":"Xinhua - Diario de Pernambuco","article_published_time":"2024-11-26T20:21:00+00:00","og_image":[{"width":388,"height":500,"url":"https:\/\/diariodepe.com.br\/xinhua\/wp-content\/uploads\/sites\/3\/2024\/07\/3.jpg","type":"image\/jpeg"}],"author":"Marcelo Oliveira de A. Maranhao","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Marcelo Oliveira de A. Maranhao","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/diariodepe.com.br\/xinhua\/2024\/11\/26\/livro-publicado-de-discursos-de-xi-sobre-governanca-das-forcas-armadas-baseadas-na-lei\/#article","isPartOf":{"@id":"https:\/\/diariodepe.com.br\/xinhua\/2024\/11\/26\/livro-publicado-de-discursos-de-xi-sobre-governanca-das-forcas-armadas-baseadas-na-lei\/"},"author":{"name":"Marcelo Oliveira de A. Maranhao","@id":"https:\/\/diariodepe.com.br\/xinhua\/#\/schema\/person\/0943d6fd02bdc7b49c8f495e8787a2cb"},"headline":"Livro publicado de discursos de Xi sobre governan\u00e7a das for\u00e7as armadas baseadas na lei","datePublished":"2024-11-26T20:21:00+00:00","mainEntityOfPage":{"@id":"https:\/\/diariodepe.com.br\/xinhua\/2024\/11\/26\/livro-publicado-de-discursos-de-xi-sobre-governanca-das-forcas-armadas-baseadas-na-lei\/"},"wordCount":175,"commentCount":0,"publisher":{"@id":"https:\/\/diariodepe.com.br\/xinhua\/#organization"},"image":{"@id":"https:\/\/diariodepe.com.br\/xinhua\/2024\/11\/26\/livro-publicado-de-discursos-de-xi-sobre-governanca-das-forcas-armadas-baseadas-na-lei\/#primaryimage"},"thumbnailUrl":"https:\/\/diariodepe.com.br\/xinhua\/wp-content\/uploads\/sites\/3\/2024\/07\/3.jpg","articleSection":["China"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/diariodepe.com.br\/xinhua\/2024\/11\/26\/livro-publicado-de-discursos-de-xi-sobre-governanca-das-forcas-armadas-baseadas-na-lei\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/diariodepe.com.br\/xinhua\/2024\/11\/26\/livro-publicado-de-discursos-de-xi-sobre-governanca-das-forcas-armadas-baseadas-na-lei\/","url":"https:\/\/diariodepe.com.br\/xinhua\/2024\/11\/26\/livro-publicado-de-discursos-de-xi-sobre-governanca-das-forcas-armadas-baseadas-na-lei\/","name":"Livro publicado de discursos de Xi sobre governan\u00e7a das for\u00e7as armadas baseadas na lei - Xinhua - Diario de Pernambuco","isPartOf":{"@id":"https:\/\/diariodepe.com.br\/xinhua\/#website"},"primaryImageOfPage":{"@id":"https:\/\/diariodepe.com.br\/xinhua\/2024\/11\/26\/livro-publicado-de-discursos-de-xi-sobre-governanca-das-forcas-armadas-baseadas-na-lei\/#primaryimage"},"image":{"@id":"https:\/\/diariodepe.com.br\/xinhua\/2024\/11\/26\/livro-publicado-de-discursos-de-xi-sobre-governanca-das-forcas-armadas-baseadas-na-lei\/#primaryimage"},"thumbnailUrl":"https:\/\/diariodepe.com.br\/xinhua\/wp-content\/uploads\/sites\/3\/2024\/07\/3.jpg","datePublished":"2024-11-26T20:21:00+00:00","breadcrumb":{"@id":"https:\/\/diariodepe.com.br\/xinhua\/2024\/11\/26\/livro-publicado-de-discursos-de-xi-sobre-governanca-das-forcas-armadas-baseadas-na-lei\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/diariodepe.com.br\/xinhua\/2024\/11\/26\/livro-publicado-de-discursos-de-xi-sobre-governanca-das-forcas-armadas-baseadas-na-lei\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/diariodepe.com.br\/xinhua\/2024\/11\/26\/livro-publicado-de-discursos-de-xi-sobre-governanca-das-forcas-armadas-baseadas-na-lei\/#primaryimage","url":"https:\/\/diariodepe.com.br\/xinhua\/wp-content\/uploads\/sites\/3\/2024\/07\/3.jpg","contentUrl":"https:\/\/diariodepe.com.br\/xinhua\/wp-content\/uploads\/sites\/3\/2024\/07\/3.jpg","width":388,"height":500,"caption":"(130907) -- ASTANA, Sept. 7, 2013 (Xinhua) -- Chinese President Xi Jinping delivers a speech at the Nazarbayev University in Astana, Kazakhstan, Sept. 7, 2013. (Xinhua\/Wang Ye) (wqq)"},{"@type":"BreadcrumbList","@id":"https:\/\/diariodepe.com.br\/xinhua\/2024\/11\/26\/livro-publicado-de-discursos-de-xi-sobre-governanca-das-forcas-armadas-baseadas-na-lei\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/diariodepe.com.br\/xinhua\/"},{"@type":"ListItem","position":2,"name":"Livro publicado de discursos de Xi sobre governan\u00e7a das for\u00e7as armadas baseadas na lei"}]},{"@type":"WebSite","@id":"https:\/\/diariodepe.com.br\/xinhua\/#website","url":"https:\/\/diariodepe.com.br\/xinhua\/","name":"Xinhua - Diario de Pernambuco","description":"A maior ag\u00eancia de not\u00edcias da China e um dos principais canais para conhecer o pa\u00eds","publisher":{"@id":"https:\/\/diariodepe.com.br\/xinhua\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/diariodepe.com.br\/xinhua\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/diariodepe.com.br\/xinhua\/#organization","name":"Xinhua - Diario de Pernambuco","url":"https:\/\/diariodepe.com.br\/xinhua\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/diariodepe.com.br\/xinhua\/#\/schema\/logo\/image\/","url":"https:\/\/diariodepe.com.br\/xinhua\/wp-content\/uploads\/sites\/3\/2020\/10\/cropped-logo-transparente-2.png","contentUrl":"https:\/\/diariodepe.com.br\/xinhua\/wp-content\/uploads\/sites\/3\/2020\/10\/cropped-logo-transparente-2.png","width":512,"height":164,"caption":"Xinhua - Diario de Pernambuco"},"image":{"@id":"https:\/\/diariodepe.com.br\/xinhua\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/diariodepe.com.br\/xinhua\/#\/schema\/person\/0943d6fd02bdc7b49c8f495e8787a2cb","name":"Marcelo Oliveira de A. Maranhao","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/f562caee940d39879c20e90eea3e4b21860c7d4c96684c23141c554824f0059c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f562caee940d39879c20e90eea3e4b21860c7d4c96684c23141c554824f0059c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f562caee940d39879c20e90eea3e4b21860c7d4c96684c23141c554824f0059c?s=96&d=mm&r=g","caption":"Marcelo Oliveira de A. Maranhao"},"url":"https:\/\/diariodepe.com.br\/xinhua\/author\/marcelo-maranhao\/"}]}},"cc_featured_image_caption":{"caption_text":"","source_text":"","source_url":""},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/diariodepe.com.br\/xinhua\/wp-json\/wp\/v2\/posts\/24080","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diariodepe.com.br\/xinhua\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diariodepe.com.br\/xinhua\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diariodepe.com.br\/xinhua\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/diariodepe.com.br\/xinhua\/wp-json\/wp\/v2\/comments?post=24080"}],"version-history":[{"count":1,"href":"https:\/\/diariodepe.com.br\/xinhua\/wp-json\/wp\/v2\/posts\/24080\/revisions"}],"predecessor-version":[{"id":24081,"href":"https:\/\/diariodepe.com.br\/xinhua\/wp-json\/wp\/v2\/posts\/24080\/revisions\/24081"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diariodepe.com.br\/xinhua\/wp-json\/wp\/v2\/media\/21056"}],"wp:attachment":[{"href":"https:\/\/diariodepe.com.br\/xinhua\/wp-json\/wp\/v2\/media?parent=24080"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diariodepe.com.br\/xinhua\/wp-json\/wp\/v2\/categories?post=24080"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diariodepe.com.br\/xinhua\/wp-json\/wp\/v2\/tags?post=24080"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}