{"id":16041,"date":"2023-10-26T09:01:00","date_gmt":"2023-10-26T12:01:00","guid":{"rendered":"https:\/\/www.diariodepe.com.br\/xinhua\/?p=16041"},"modified":"2023-10-26T08:06:52","modified_gmt":"2023-10-26T11:06:52","slug":"trem-de-emu-da-ferrovia-de-alta-velocidade-jacarta-bandung-carrega-esperancas-rumo-ao-futuro","status":"publish","type":"post","link":"https:\/\/diariodepe.com.br\/xinhua\/2023\/10\/26\/trem-de-emu-da-ferrovia-de-alta-velocidade-jacarta-bandung-carrega-esperancas-rumo-ao-futuro\/","title":{"rendered":"Trem de EMU da Ferrovia de Alta Velocidade Jacarta-Bandung carrega esperan\u00e7as rumo ao futuro"},"content":{"rendered":"\n<p>Por Xu Qin e Yu Qianliang<\/p>\n\n\n\n<p>Jacarta &#8211; Os adolescentes indon\u00e9sios sentem o charme da &#8220;Velocidade da China&#8221; e iluminam seus sonhos para o futuro.<\/p>\n\n\n\n<p>Na ter\u00e7a-feira, a Base de Interc\u00e2mbio Educacional e Cultural da Unidade M\u00faltipla El\u00e9trica (EMU) da Ferrovia de Alta Velocidade (HSR, em ingl\u00eas) Jacarta-Bandung conduziu uma aula gratuita para a Escola Secund\u00e1ria Ngamprah No.3 em West Bandung Regency, na Prov\u00edncia de Java Ocidental.<\/p>\n\n\n\n<p>Especialistas t\u00e9cnicos chineses em ferrovias de alta velocidade da China Railway Rolling Stock Corporation (CRRC) Sifang Co., Ltd., a empresa que projetou e fabricou os trens de EMU da HSR Jacarta-Bandung, visitaram o campus da escola para ministrar cursos de ci\u00eancias da HSR para os alunos locais e levaram os adolescentes indon\u00e9sios a experimentar o charme imersivo da &#8220;Velocidade da China&#8221; em um trem de EMU da HSR Jacarta-Bandung em funcionamento.<\/p>\n\n\n\n<p>&#8220;Meninos e meninas, quem pode me dizer por que os trens da Ferrovia de Alta Velocidade Jacarta-Bandung podem andar t\u00e3o r\u00e1pido?&#8221; Na sala de aula, Zhang Fangtao, projetista-chefe dos trens de EMU da HSR Jacarta-Bandung, adquiriu uma nova identidade como professor de ci\u00eancias que lecionou sobre a ci\u00eancia da HSR.<\/p>\n\n\n\n<p>Na sala de aula, que fica pr\u00f3xima a uma linha ferrovi\u00e1ria tradicional e \u00e0 Esta\u00e7\u00e3o de Padalarang da HSR Jacarta-Bandung, os alunos curiosos ouviram atentamente o professor de ci\u00eancias e levantaram as m\u00e3os ativamente para responder \u00e0s perguntas.<\/p>\n\n\n\n<p>O clima na sala de aula de 40 m\u00b2 era animado, com intera\u00e7\u00f5es frequentes e perguntas e respostas entre Zhang e os alunos, pontuadas por risadas e aplausos.<\/p>\n\n\n\n<p>Saskia, uma aluna de 15 anos do 9\u00ba ano, disse: &#8220;Reduzir a viagem entre Jacarta e Bandung de mais de tr\u00eas horas para cerca de 40 minutos \u00e9 muito legal, acho que o trem de alta velocidade \u00e9 uma boa escolha para muitas pessoas&#8221;.<\/p>\n\n\n\n<p>O ensino em sala de aula foi seguido por uma experi\u00eancia no local, dentro do vag\u00e3o de um trem de EMU em funcionamento, da Esta\u00e7\u00e3o de Padalarang at\u00e9 a Esta\u00e7\u00e3o de Halim da HSR Jacarta-Bandung. As risadas dos adolescentes e o som do obturador de seus telefones celulares preencheram todo o vag\u00e3o do trem que passava rapidamente por campos, rios, montanhas e plan\u00edcies da Ilha de Java.<\/p>\n\n\n\n<p>Zhang, mais uma vez, deu uma aula&nbsp;sobre a ci\u00eancia da HSR, mas dessa vez a sala de aula estava em movimento, em um trem de alta velocidade de verdade, e ele teve que chamar a aten\u00e7\u00e3o dos adolescentes com exclama\u00e7\u00f5es frequentes e paisagens fugazes do lado de fora da janela do trem.<\/p>\n\n\n\n<p>&#8220;Depois que a opera\u00e7\u00e3o comercial come\u00e7ou na semana passada, finalmente tive a oportunidade de andar no trem de alta velocidade. Durante a fase de viagem gratuita, meus pais tentaram em v\u00e3o conseguir uma passagem para mim&#8221;, disse Rayi, 14 anos, outro aluno do 9\u00ba ano. &#8220;Aprendi muito sobre a HSR hoje na aula e no trem, e mal posso esperar para ser um empres\u00e1rio no futuro e viajar no trem de alta velocidade.&#8221;&nbsp;<\/p>\n\n\n\n<p>Al\u00e9m das aulas dentro e fora da sala de aula, a CRRC Sifang doou materiais did\u00e1ticos, incluindo computadores e sistemas de som, para a Escola Secund\u00e1ria Ngamprah No.3.<\/p>\n\n\n\n<p>A escola \u00e9 uma escola p\u00fablica pequena, com centenas de alunos e apenas algumas salas de aula usadas por alunos da 7\u00aa \u00e0 9\u00aa s\u00e9rie em regime de rod\u00edzio.<\/p>\n\n\n\n<p>&#8220;Sou muito grato a essas empresas chinesas por apoiarem o desenvolvimento da educa\u00e7\u00e3o em Bandung Ocidental. A CRRC Sifang doa materiais did\u00e1ticos para nossa escola, o que pode nos ajudar a melhorar a qualidade da educa\u00e7\u00e3o&#8221;, disse Mepi, diretor da escola secund\u00e1ria.<\/p>\n\n\n\n<p>&#8220;As aulas e a experi\u00eancia da HSR ajudaram a ampliar os horizontes dos alunos, abrindo a porta para um novo mundo para nossas crian\u00e7as.&#8221;<\/p>\n\n\n\n<p>Asep Wahyu, assistente de economia e desenvolvimento da Reg\u00eancia de Bandung Ocidental, disse: &#8220;\u00c9 realmente generoso o fato de a CRRC Sifang prestar assist\u00eancia \u00e0 nossa escola local. Os materiais did\u00e1ticos e as aulas gratuitas ajudar\u00e3o nossos alunos a estudar melhor&#8221;.<\/p>\n\n\n\n<p>&#8220;Ouvi dizer que os chineses chamam as crian\u00e7as de &#8216;flores do pa\u00eds&#8217;, e os indon\u00e9sios t\u00eam um ditado semelhante, chamando nossos filhos de &#8216;brotos do pa\u00eds&#8217;, seja flor ou broto, eles s\u00e3o o futuro, s\u00e3o nossa esperan\u00e7a&#8221;, acrescentou Asep.<\/p>\n\n\n\n<p>A HSR Jakarta-Bandung \u00e9 uma &#8220;marca de ouro&#8221; da coopera\u00e7\u00e3o China-Indon\u00e9sia sob a Iniciativa Cintur\u00e3o e Rota (ICR) proposta pela China. \u00c9 a primeira ferrovia de alta velocidade da Indon\u00e9sia e do Sudeste Asi\u00e1tico em geral. A CRRC Sifang, como parte do projeto da HSR Jakarta-Bandung, projeta e fabrica trens de EMU de alta velocidade com velocidade operacional m\u00e1xima de 350 km por hora para a ferrovia.<\/p>\n\n\n\n<p>&#8220;A ferrovia de alta velocidade Jacarta-Bandung n\u00e3o \u00e9 apenas um s\u00edmbolo da coopera\u00e7\u00e3o vantajosa para ambas as partes entre a China e a Indon\u00e9sia, mas tamb\u00e9m uma ponte de liga\u00e7\u00e3o para aumentar a amizade entre nossas duas na\u00e7\u00f5es&#8221;, disse Cao Rui, vice-gerente geral da CRRC Sifang.<\/p>\n\n\n\n<p>A HSR Jacarta-Bandung, constru\u00eddo em conjunto pela China e pela Indon\u00e9sia, foi oficialmente colocado em opera\u00e7\u00e3o comercial em 17 de outubro.<\/p>\n\n\n\n<p>A Base de Interc\u00e2mbio Educacional e Cultural da EMU da HSR Jakarta-Bandung foi estabelecida em Bandung, Java Ocidental, Indon\u00e9sia, em 9 de setembro.&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por Xu Qin e Yu Qianliang Jacarta &#8211; Os adolescentes indon\u00e9sios sentem o charme da &#8220;Velocidade da China&#8221; e iluminam seus sonhos para o futuro. Na ter\u00e7a-feira, a Base de Interc\u00e2mbio Educacional e Cultural da Unidade M\u00faltipla El\u00e9trica (EMU) da&#8230;<\/p>\n","protected":false},"author":3,"featured_media":16042,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-16041","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geral"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Trem de EMU da Ferrovia de Alta Velocidade Jacarta-Bandung carrega esperan\u00e7as rumo ao futuro - Xinhua - Diario de Pernambuco<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/diariodepe.com.br\/xinhua\/2023\/10\/26\/trem-de-emu-da-ferrovia-de-alta-velocidade-jacarta-bandung-carrega-esperancas-rumo-ao-futuro\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Trem de EMU da Ferrovia de Alta Velocidade Jacarta-Bandung carrega esperan\u00e7as rumo ao futuro - Xinhua - Diario de Pernambuco\" \/>\n<meta property=\"og:description\" content=\"Por Xu Qin e Yu Qianliang Jacarta &#8211; Os adolescentes indon\u00e9sios sentem o charme da &#8220;Velocidade da China&#8221; e iluminam seus sonhos para o futuro. Na ter\u00e7a-feira, a Base de Interc\u00e2mbio Educacional e Cultural da Unidade M\u00faltipla El\u00e9trica (EMU) da...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/diariodepe.com.br\/xinhua\/2023\/10\/26\/trem-de-emu-da-ferrovia-de-alta-velocidade-jacarta-bandung-carrega-esperancas-rumo-ao-futuro\/\" \/>\n<meta property=\"og:site_name\" content=\"Xinhua - Diario de Pernambuco\" \/>\n<meta property=\"article:published_time\" content=\"2023-10-26T12:01:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/diariodepe.com.br\/xinhua\/wp-content\/uploads\/sites\/3\/2023\/10\/202310267d3ba2a4c4414ecca0b4c098f5a89de1_202310261a24af2d1f5046efa33b2a35edab558c.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"683\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Marcelo Oliveira de A. Maranhao\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Marcelo Oliveira de A. Maranhao\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/diariodepe.com.br\\\/xinhua\\\/2023\\\/10\\\/26\\\/trem-de-emu-da-ferrovia-de-alta-velocidade-jacarta-bandung-carrega-esperancas-rumo-ao-futuro\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diariodepe.com.br\\\/xinhua\\\/2023\\\/10\\\/26\\\/trem-de-emu-da-ferrovia-de-alta-velocidade-jacarta-bandung-carrega-esperancas-rumo-ao-futuro\\\/\"},\"author\":{\"name\":\"Marcelo Oliveira de A. Maranhao\",\"@id\":\"https:\\\/\\\/diariodepe.com.br\\\/xinhua\\\/#\\\/schema\\\/person\\\/0943d6fd02bdc7b49c8f495e8787a2cb\"},\"headline\":\"Trem de EMU da Ferrovia de Alta Velocidade Jacarta-Bandung carrega esperan\u00e7as rumo ao futuro\",\"datePublished\":\"2023-10-26T12:01:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/diariodepe.com.br\\\/xinhua\\\/2023\\\/10\\\/26\\\/trem-de-emu-da-ferrovia-de-alta-velocidade-jacarta-bandung-carrega-esperancas-rumo-ao-futuro\\\/\"},\"wordCount\":925,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/diariodepe.com.br\\\/xinhua\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/diariodepe.com.br\\\/xinhua\\\/2023\\\/10\\\/26\\\/trem-de-emu-da-ferrovia-de-alta-velocidade-jacarta-bandung-carrega-esperancas-rumo-ao-futuro\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/diariodepe.com.br\\\/xinhua\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2023\\\/10\\\/202310267d3ba2a4c4414ecca0b4c098f5a89de1_202310261a24af2d1f5046efa33b2a35edab558c.png\",\"articleSection\":[\"Geral\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/diariodepe.com.br\\\/xinhua\\\/2023\\\/10\\\/26\\\/trem-de-emu-da-ferrovia-de-alta-velocidade-jacarta-bandung-carrega-esperancas-rumo-ao-futuro\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/diariodepe.com.br\\\/xinhua\\\/2023\\\/10\\\/26\\\/trem-de-emu-da-ferrovia-de-alta-velocidade-jacarta-bandung-carrega-esperancas-rumo-ao-futuro\\\/\",\"url\":\"https:\\\/\\\/diariodepe.com.br\\\/xinhua\\\/2023\\\/10\\\/26\\\/trem-de-emu-da-ferrovia-de-alta-velocidade-jacarta-bandung-carrega-esperancas-rumo-ao-futuro\\\/\",\"name\":\"Trem de EMU da Ferrovia de Alta Velocidade Jacarta-Bandung carrega esperan\u00e7as rumo ao futuro - Xinhua - Diario de Pernambuco\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diariodepe.com.br\\\/xinhua\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/diariodepe.com.br\\\/xinhua\\\/2023\\\/10\\\/26\\\/trem-de-emu-da-ferrovia-de-alta-velocidade-jacarta-bandung-carrega-esperancas-rumo-ao-futuro\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/diariodepe.com.br\\\/xinhua\\\/2023\\\/10\\\/26\\\/trem-de-emu-da-ferrovia-de-alta-velocidade-jacarta-bandung-carrega-esperancas-rumo-ao-futuro\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/diariodepe.com.br\\\/xinhua\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2023\\\/10\\\/202310267d3ba2a4c4414ecca0b4c098f5a89de1_202310261a24af2d1f5046efa33b2a35edab558c.png\",\"datePublished\":\"2023-10-26T12:01:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/diariodepe.com.br\\\/xinhua\\\/2023\\\/10\\\/26\\\/trem-de-emu-da-ferrovia-de-alta-velocidade-jacarta-bandung-carrega-esperancas-rumo-ao-futuro\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/diariodepe.com.br\\\/xinhua\\\/2023\\\/10\\\/26\\\/trem-de-emu-da-ferrovia-de-alta-velocidade-jacarta-bandung-carrega-esperancas-rumo-ao-futuro\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/diariodepe.com.br\\\/xinhua\\\/2023\\\/10\\\/26\\\/trem-de-emu-da-ferrovia-de-alta-velocidade-jacarta-bandung-carrega-esperancas-rumo-ao-futuro\\\/#primaryimage\",\"url\":\"https:\\\/\\\/diariodepe.com.br\\\/xinhua\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2023\\\/10\\\/202310267d3ba2a4c4414ecca0b4c098f5a89de1_202310261a24af2d1f5046efa33b2a35edab558c.png\",\"contentUrl\":\"https:\\\/\\\/diariodepe.com.br\\\/xinhua\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2023\\\/10\\\/202310267d3ba2a4c4414ecca0b4c098f5a89de1_202310261a24af2d1f5046efa33b2a35edab558c.png\",\"width\":1024,\"height\":683},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/diariodepe.com.br\\\/xinhua\\\/2023\\\/10\\\/26\\\/trem-de-emu-da-ferrovia-de-alta-velocidade-jacarta-bandung-carrega-esperancas-rumo-ao-futuro\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/diariodepe.com.br\\\/xinhua\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Trem de EMU da Ferrovia de Alta Velocidade Jacarta-Bandung carrega esperan\u00e7as rumo ao futuro\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/diariodepe.com.br\\\/xinhua\\\/#website\",\"url\":\"https:\\\/\\\/diariodepe.com.br\\\/xinhua\\\/\",\"name\":\"Xinhua - Diario de Pernambuco\",\"description\":\"A maior ag\u00eancia de not\u00edcias da China e um dos principais canais para conhecer o pa\u00eds\",\"publisher\":{\"@id\":\"https:\\\/\\\/diariodepe.com.br\\\/xinhua\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/diariodepe.com.br\\\/xinhua\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/diariodepe.com.br\\\/xinhua\\\/#organization\",\"name\":\"Xinhua - Diario de Pernambuco\",\"url\":\"https:\\\/\\\/diariodepe.com.br\\\/xinhua\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/diariodepe.com.br\\\/xinhua\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/diariodepe.com.br\\\/xinhua\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2020\\\/10\\\/cropped-logo-transparente-2.png\",\"contentUrl\":\"https:\\\/\\\/diariodepe.com.br\\\/xinhua\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2020\\\/10\\\/cropped-logo-transparente-2.png\",\"width\":512,\"height\":164,\"caption\":\"Xinhua - Diario de Pernambuco\"},\"image\":{\"@id\":\"https:\\\/\\\/diariodepe.com.br\\\/xinhua\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/diariodepe.com.br\\\/xinhua\\\/#\\\/schema\\\/person\\\/0943d6fd02bdc7b49c8f495e8787a2cb\",\"name\":\"Marcelo Oliveira de A. Maranhao\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f562caee940d39879c20e90eea3e4b21860c7d4c96684c23141c554824f0059c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f562caee940d39879c20e90eea3e4b21860c7d4c96684c23141c554824f0059c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f562caee940d39879c20e90eea3e4b21860c7d4c96684c23141c554824f0059c?s=96&d=mm&r=g\",\"caption\":\"Marcelo Oliveira de A. Maranhao\"},\"url\":\"https:\\\/\\\/diariodepe.com.br\\\/xinhua\\\/author\\\/marcelo-maranhao\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Trem de EMU da Ferrovia de Alta Velocidade Jacarta-Bandung carrega esperan\u00e7as rumo ao futuro - Xinhua - Diario de Pernambuco","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/diariodepe.com.br\/xinhua\/2023\/10\/26\/trem-de-emu-da-ferrovia-de-alta-velocidade-jacarta-bandung-carrega-esperancas-rumo-ao-futuro\/","og_locale":"pt_BR","og_type":"article","og_title":"Trem de EMU da Ferrovia de Alta Velocidade Jacarta-Bandung carrega esperan\u00e7as rumo ao futuro - Xinhua - Diario de Pernambuco","og_description":"Por Xu Qin e Yu Qianliang Jacarta &#8211; Os adolescentes indon\u00e9sios sentem o charme da &#8220;Velocidade da China&#8221; e iluminam seus sonhos para o futuro. Na ter\u00e7a-feira, a Base de Interc\u00e2mbio Educacional e Cultural da Unidade M\u00faltipla El\u00e9trica (EMU) da...","og_url":"https:\/\/diariodepe.com.br\/xinhua\/2023\/10\/26\/trem-de-emu-da-ferrovia-de-alta-velocidade-jacarta-bandung-carrega-esperancas-rumo-ao-futuro\/","og_site_name":"Xinhua - Diario de Pernambuco","article_published_time":"2023-10-26T12:01:00+00:00","og_image":[{"width":1024,"height":683,"url":"https:\/\/diariodepe.com.br\/xinhua\/wp-content\/uploads\/sites\/3\/2023\/10\/202310267d3ba2a4c4414ecca0b4c098f5a89de1_202310261a24af2d1f5046efa33b2a35edab558c.png","type":"image\/png"}],"author":"Marcelo Oliveira de A. Maranhao","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Marcelo Oliveira de A. Maranhao","Est. tempo de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/diariodepe.com.br\/xinhua\/2023\/10\/26\/trem-de-emu-da-ferrovia-de-alta-velocidade-jacarta-bandung-carrega-esperancas-rumo-ao-futuro\/#article","isPartOf":{"@id":"https:\/\/diariodepe.com.br\/xinhua\/2023\/10\/26\/trem-de-emu-da-ferrovia-de-alta-velocidade-jacarta-bandung-carrega-esperancas-rumo-ao-futuro\/"},"author":{"name":"Marcelo Oliveira de A. Maranhao","@id":"https:\/\/diariodepe.com.br\/xinhua\/#\/schema\/person\/0943d6fd02bdc7b49c8f495e8787a2cb"},"headline":"Trem de EMU da Ferrovia de Alta Velocidade Jacarta-Bandung carrega esperan\u00e7as rumo ao futuro","datePublished":"2023-10-26T12:01:00+00:00","mainEntityOfPage":{"@id":"https:\/\/diariodepe.com.br\/xinhua\/2023\/10\/26\/trem-de-emu-da-ferrovia-de-alta-velocidade-jacarta-bandung-carrega-esperancas-rumo-ao-futuro\/"},"wordCount":925,"commentCount":0,"publisher":{"@id":"https:\/\/diariodepe.com.br\/xinhua\/#organization"},"image":{"@id":"https:\/\/diariodepe.com.br\/xinhua\/2023\/10\/26\/trem-de-emu-da-ferrovia-de-alta-velocidade-jacarta-bandung-carrega-esperancas-rumo-ao-futuro\/#primaryimage"},"thumbnailUrl":"https:\/\/diariodepe.com.br\/xinhua\/wp-content\/uploads\/sites\/3\/2023\/10\/202310267d3ba2a4c4414ecca0b4c098f5a89de1_202310261a24af2d1f5046efa33b2a35edab558c.png","articleSection":["Geral"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/diariodepe.com.br\/xinhua\/2023\/10\/26\/trem-de-emu-da-ferrovia-de-alta-velocidade-jacarta-bandung-carrega-esperancas-rumo-ao-futuro\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/diariodepe.com.br\/xinhua\/2023\/10\/26\/trem-de-emu-da-ferrovia-de-alta-velocidade-jacarta-bandung-carrega-esperancas-rumo-ao-futuro\/","url":"https:\/\/diariodepe.com.br\/xinhua\/2023\/10\/26\/trem-de-emu-da-ferrovia-de-alta-velocidade-jacarta-bandung-carrega-esperancas-rumo-ao-futuro\/","name":"Trem de EMU da Ferrovia de Alta Velocidade Jacarta-Bandung carrega esperan\u00e7as rumo ao futuro - Xinhua - Diario de Pernambuco","isPartOf":{"@id":"https:\/\/diariodepe.com.br\/xinhua\/#website"},"primaryImageOfPage":{"@id":"https:\/\/diariodepe.com.br\/xinhua\/2023\/10\/26\/trem-de-emu-da-ferrovia-de-alta-velocidade-jacarta-bandung-carrega-esperancas-rumo-ao-futuro\/#primaryimage"},"image":{"@id":"https:\/\/diariodepe.com.br\/xinhua\/2023\/10\/26\/trem-de-emu-da-ferrovia-de-alta-velocidade-jacarta-bandung-carrega-esperancas-rumo-ao-futuro\/#primaryimage"},"thumbnailUrl":"https:\/\/diariodepe.com.br\/xinhua\/wp-content\/uploads\/sites\/3\/2023\/10\/202310267d3ba2a4c4414ecca0b4c098f5a89de1_202310261a24af2d1f5046efa33b2a35edab558c.png","datePublished":"2023-10-26T12:01:00+00:00","breadcrumb":{"@id":"https:\/\/diariodepe.com.br\/xinhua\/2023\/10\/26\/trem-de-emu-da-ferrovia-de-alta-velocidade-jacarta-bandung-carrega-esperancas-rumo-ao-futuro\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/diariodepe.com.br\/xinhua\/2023\/10\/26\/trem-de-emu-da-ferrovia-de-alta-velocidade-jacarta-bandung-carrega-esperancas-rumo-ao-futuro\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/diariodepe.com.br\/xinhua\/2023\/10\/26\/trem-de-emu-da-ferrovia-de-alta-velocidade-jacarta-bandung-carrega-esperancas-rumo-ao-futuro\/#primaryimage","url":"https:\/\/diariodepe.com.br\/xinhua\/wp-content\/uploads\/sites\/3\/2023\/10\/202310267d3ba2a4c4414ecca0b4c098f5a89de1_202310261a24af2d1f5046efa33b2a35edab558c.png","contentUrl":"https:\/\/diariodepe.com.br\/xinhua\/wp-content\/uploads\/sites\/3\/2023\/10\/202310267d3ba2a4c4414ecca0b4c098f5a89de1_202310261a24af2d1f5046efa33b2a35edab558c.png","width":1024,"height":683},{"@type":"BreadcrumbList","@id":"https:\/\/diariodepe.com.br\/xinhua\/2023\/10\/26\/trem-de-emu-da-ferrovia-de-alta-velocidade-jacarta-bandung-carrega-esperancas-rumo-ao-futuro\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/diariodepe.com.br\/xinhua\/"},{"@type":"ListItem","position":2,"name":"Trem de EMU da Ferrovia de Alta Velocidade Jacarta-Bandung carrega esperan\u00e7as rumo ao futuro"}]},{"@type":"WebSite","@id":"https:\/\/diariodepe.com.br\/xinhua\/#website","url":"https:\/\/diariodepe.com.br\/xinhua\/","name":"Xinhua - Diario de Pernambuco","description":"A maior ag\u00eancia de not\u00edcias da China e um dos principais canais para conhecer o pa\u00eds","publisher":{"@id":"https:\/\/diariodepe.com.br\/xinhua\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/diariodepe.com.br\/xinhua\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/diariodepe.com.br\/xinhua\/#organization","name":"Xinhua - Diario de Pernambuco","url":"https:\/\/diariodepe.com.br\/xinhua\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/diariodepe.com.br\/xinhua\/#\/schema\/logo\/image\/","url":"https:\/\/diariodepe.com.br\/xinhua\/wp-content\/uploads\/sites\/3\/2020\/10\/cropped-logo-transparente-2.png","contentUrl":"https:\/\/diariodepe.com.br\/xinhua\/wp-content\/uploads\/sites\/3\/2020\/10\/cropped-logo-transparente-2.png","width":512,"height":164,"caption":"Xinhua - Diario de Pernambuco"},"image":{"@id":"https:\/\/diariodepe.com.br\/xinhua\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/diariodepe.com.br\/xinhua\/#\/schema\/person\/0943d6fd02bdc7b49c8f495e8787a2cb","name":"Marcelo Oliveira de A. Maranhao","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/f562caee940d39879c20e90eea3e4b21860c7d4c96684c23141c554824f0059c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f562caee940d39879c20e90eea3e4b21860c7d4c96684c23141c554824f0059c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f562caee940d39879c20e90eea3e4b21860c7d4c96684c23141c554824f0059c?s=96&d=mm&r=g","caption":"Marcelo Oliveira de A. Maranhao"},"url":"https:\/\/diariodepe.com.br\/xinhua\/author\/marcelo-maranhao\/"}]}},"cc_featured_image_caption":{"caption_text":"","source_text":"","source_url":""},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/diariodepe.com.br\/xinhua\/wp-json\/wp\/v2\/posts\/16041","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diariodepe.com.br\/xinhua\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diariodepe.com.br\/xinhua\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diariodepe.com.br\/xinhua\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/diariodepe.com.br\/xinhua\/wp-json\/wp\/v2\/comments?post=16041"}],"version-history":[{"count":1,"href":"https:\/\/diariodepe.com.br\/xinhua\/wp-json\/wp\/v2\/posts\/16041\/revisions"}],"predecessor-version":[{"id":16043,"href":"https:\/\/diariodepe.com.br\/xinhua\/wp-json\/wp\/v2\/posts\/16041\/revisions\/16043"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diariodepe.com.br\/xinhua\/wp-json\/wp\/v2\/media\/16042"}],"wp:attachment":[{"href":"https:\/\/diariodepe.com.br\/xinhua\/wp-json\/wp\/v2\/media?parent=16041"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diariodepe.com.br\/xinhua\/wp-json\/wp\/v2\/categories?post=16041"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diariodepe.com.br\/xinhua\/wp-json\/wp\/v2\/tags?post=16041"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}