{"id":13514,"date":"2023-06-12T13:47:14","date_gmt":"2023-06-12T16:47:14","guid":{"rendered":"https:\/\/www.diariodepe.com.br\/xinhua\/?p=13514"},"modified":"2023-06-12T13:47:17","modified_gmt":"2023-06-12T16:47:17","slug":"de-risking-deveria-ter-como-alvo-riscos-ocidentais-reais","status":"publish","type":"post","link":"https:\/\/diariodepe.com.br\/xinhua\/2023\/06\/12\/de-risking-deveria-ter-como-alvo-riscos-ocidentais-reais\/","title":{"rendered":"&#8220;De-risking&#8221; deveria ter como alvo riscos ocidentais reais"},"content":{"rendered":"\n<ul class=\"wp-block-list\"><li>O mundo n\u00e3o precisa do &#8220;de-risking&#8221; que visa a China, mas sim reduzir urgentemente os riscos que visam uma mentalidade com base em ideologia, confronto em bloco, exclusividade e hegemonia, riscos reais do Ocidente.<\/li><li>Alguns pol\u00edticos ocidentais deveriam deixar o orgulho e o preconceito de lado e se adaptarem \u00e0s realidades e necessidades de desenvolvimento do mundo multipolarizado.<\/li><\/ul>\n\n\n\n<p>Beijing &#8212; Alguns pa\u00edses desenvolvidos liderados pelos Estados Unidos substitu\u00edram o &#8220;desacoplamento&#8221; pelo &#8220;de-risking&#8221; (redu\u00e7\u00e3o de riscos, em tradu\u00e7\u00e3o livre) para atingir a China, mas isso n\u00e3o \u00e9 novidade, e h\u00e1 pouca diferen\u00e7a entre esses termos. Uma an\u00e1lise objetiva provar\u00e1 que a chamada proposi\u00e7\u00e3o de &#8220;de-risking&#8221; \u00e9 il\u00f3gica e invi\u00e1vel.<\/p>\n\n\n\n<p>Os riscos devem ser detectados primeiro quando se trata de &#8220;de-risking&#8221;. Muitas amea\u00e7as realistas e urgentes \u00e0 paz, \u00e0 prosperidade e ao bem-estar da humanidade v\u00eam dos pa\u00edses que pregam a ret\u00f3rica contra a China. E esses s\u00e3o riscos reais que precisam ser reduzidos.<\/p>\n\n\n\n<p>Sem mencionar as p\u00e9ssimas consequ\u00eancias das invas\u00f5es militares ocidentais em pa\u00edses como o Iraque e nas \u00faltimas d\u00e9cadas, as frequentes exibi\u00e7\u00f5es militares provocativas de algumas pot\u00eancias perto de outras, mas a milhares de quil\u00f4metros de suas terras, representam graves riscos para o mundo. Somente no ano passado, os Estados Unidos enviaram grupos de ataque de porta-avi\u00f5es para o Mar da China Meridional e \u00e1reas pr\u00f3ximas v\u00e1rias vezes, e as grandes aeronaves de reconhecimento fizeram mais de 800 voos pr\u00f3ximos para espionar a China.<\/p>\n\n\n\n<p>A parceria trilateral de seguran\u00e7a AUKUS dos Estados Unidos, Gr\u00e3-Bretanha e Austr\u00e1lia e a coopera\u00e7\u00e3o relacionada com submarinos nucleares criam riscos de prolifera\u00e7\u00e3o nuclear e podem transformar a regi\u00e3o em um campo de corrida armamentista. Um movimento t\u00e3o perigoso levantou fortes preocupa\u00e7\u00f5es entre os pa\u00edses da regi\u00e3o. O apoio e a coniv\u00eancia de for\u00e7as estrangeiras para os separatistas da &#8220;independ\u00eancia de Taiwan&#8221; amea\u00e7am a paz e a estabilidade no Estreito de Taiwan. Os pol\u00edticos ocidentais devem refletir sobre suas a\u00e7\u00f5es e parar com os atos irrespons\u00e1veis que amea\u00e7am a paz regional e mundial.<\/p>\n\n\n\n<p>De uma perspectiva econ\u00f4mica, o &#8220;de-risking&#8221; significa desglobaliza\u00e7\u00e3o. Alguns pa\u00edses alegaram que isso limitaria o com\u00e9rcio e o investimento com a China. Desde que ingressou na Organiza\u00e7\u00e3o Mundial do Com\u00e9rcio em 2001, a economia da China integrou-se extensivamente \u00e0 economia global. Com o desenvolvimento das divis\u00f5es industriais internacionais, nenhum pa\u00eds pode manter a supremacia em todos os setores e produzir todos os bens por conta pr\u00f3pria. Os Estados Unidos recorreram repetidamente ao uso do poder do governo para suprimir a Huawei e outras empresas de tecnologia chinesas. Os atos de politizar quest\u00f5es comerciais e de ci\u00eancia e tecnologia e ampliar muito o conceito de seguran\u00e7a nacional para suprimir empresas de outros pa\u00edses desestabilizam as cadeias industriais e de suprimentos globais.<\/p>\n\n\n\n<p>Como um mestre da coer\u00e7\u00e3o econ\u00f4mica, os Estados Unidos tamb\u00e9m coagiram abertamente a UE e alguns pa\u00edses a restringir a exporta\u00e7\u00e3o de equipamentos de fabrica\u00e7\u00e3o de semicondutores para a China. Esses atos de intimida\u00e7\u00e3o tecnol\u00f3gica prejudicam severamente o desenvolvimento do setor de semicondutores e reduzem as regras comerciais multilaterais e a ordem econ\u00f4mica global. Pior ainda, Washington h\u00e1 muito tempo usa a hegemonia do d\u00f3lar, muda crises e espalha a infla\u00e7\u00e3o dos EUA para outras partes do mundo, piorando os problemas econ\u00f4micos em alguns pa\u00edses em desenvolvimento e atrasando seriamente a recupera\u00e7\u00e3o global. Esses s\u00e3o os grandes riscos que precisam ser abordados.<\/p>\n\n\n\n<p>No entanto, apesar do assunto &#8220;de-risking&#8221;, as empresas globais t\u00eam sua pr\u00f3pria posi\u00e7\u00e3o. A marca de restaurantes americana Subway anunciou esta semana que firmou um novo contrato de franquia master com uma empresa sediada em Shanghai para expandir a presen\u00e7a na China. Um relat\u00f3rio divulgado pela C\u00e2mara de Com\u00e9rcio da UE na China indica que cerca de 60% das empresas pesquisadas disseram que aumentariam os gastos com P&amp;D na China nos pr\u00f3ximos cinco anos. Uma pesquisa da AmCham China mostra que 66% das empresas americanas na China manter\u00e3o ou aumentar\u00e3o o investimento no pa\u00eds nos pr\u00f3ximos dois anos.<\/p>\n\n\n\n<p>A maioria dos europeus v\u00ea a China como &#8220;um parceiro necess\u00e1rio&#8221;, de acordo com a \u00faltima pesquisa do Conselho Europeu de Rela\u00e7\u00f5es Exteriores. A Airbus construir\u00e1 uma segunda linha de montagem final em Tianjin. Durante uma recente visita \u00e0 China, Elon Musk, fundador da Tesla, disse que os interesses dos Estados Unidos e da China est\u00e3o conectados, como g\u00eameos insepar\u00e1veis. A Tesla construir\u00e1 uma nova megaf\u00e1brica para produtos de armazenamento de energia em Shanghai este ano.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"900\" height=\"593\" src=\"http:\/\/www.diariodepe.com.br\/xinhua\/wp-content\/uploads\/2023\/06\/2023061268e55884caff4b9ab98bc5afb2a34a0d_20230612c9d3ad07b50e41c6a45d4dd3db0d562c.png\" alt=\"\" class=\"wp-image-13516\" srcset=\"https:\/\/diariodepe.com.br\/xinhua\/wp-content\/uploads\/sites\/3\/2023\/06\/2023061268e55884caff4b9ab98bc5afb2a34a0d_20230612c9d3ad07b50e41c6a45d4dd3db0d562c.png 900w, https:\/\/diariodepe.com.br\/xinhua\/wp-content\/uploads\/sites\/3\/2023\/06\/2023061268e55884caff4b9ab98bc5afb2a34a0d_20230612c9d3ad07b50e41c6a45d4dd3db0d562c-300x198.png 300w, https:\/\/diariodepe.com.br\/xinhua\/wp-content\/uploads\/sites\/3\/2023\/06\/2023061268e55884caff4b9ab98bc5afb2a34a0d_20230612c9d3ad07b50e41c6a45d4dd3db0d562c-768x506.png 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><figcaption>Carro da Tesla \u00e9 exibido na terceira Exposi\u00e7\u00e3o Internacional de Produtos de Consumo da China (CICPE, na sigla em ingl\u00eas) em Haikou, capital da prov\u00edncia de Hainan, sul da China, no dia 11 de abril de 2023. Foyo: Fan Yuqing<\/figcaption><\/figure>\n\n\n\n<p>A China est\u00e1 comprometida com o desenvolvimento pac\u00edfico, uma estrat\u00e9gia m\u00fatua de abertura e com o fornecimento de um ambiente de neg\u00f3cios internacionalizado, com base na lei e orientado para o mercado para empresas de todos os pa\u00edses. Na \u00faltima d\u00e9cada, a China foi respons\u00e1vel por mais crescimento econ\u00f4mico mundial em m\u00e9dia anual do que todos os membros do G7 juntos. A China traz oportunidades, estabilidade e seguran\u00e7a para o mundo.<\/p>\n\n\n\n<p>A comunidade internacional se op\u00f5e cada vez mais \u00e0 hipocrisia e hegemonia ocidentais nas rela\u00e7\u00f5es internacionais. Alguns pol\u00edticos ocidentais devem deixar o orgulho e o preconceito de lado e se adaptarem \u00e0s realidades e necessidades de desenvolvimento do mundo multipolarizado, al\u00e9m de buscar a paz e a prosperidade compartilhadas, em vez de incentivar confrontos e criar riscos e caos.<\/p>\n\n\n\n<p>O mundo n\u00e3o precisa do chamado &#8220;de-risking&#8221; que visa a China, mas sim reduzir urgentemente os riscos que visam uma mentalidade com base em ideologia, confronto em bloco, exclusividade e hegemonia, riscos reais do Ocidente.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O mundo n\u00e3o precisa do &#8220;de-risking&#8221; que visa a China, mas sim reduzir urgentemente os riscos que visam uma mentalidade com base em ideologia, confronto em bloco, exclusividade e hegemonia, riscos reais do Ocidente. Alguns pol\u00edticos ocidentais deveriam deixar o&#8230;<\/p>\n","protected":false},"author":6,"featured_media":13515,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-13514","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internacional"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>&quot;De-risking&quot; deveria ter como alvo riscos ocidentais reais - Xinhua - Diario de Pernambuco<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/diariodepe.com.br\/xinhua\/2023\/06\/12\/de-risking-deveria-ter-como-alvo-riscos-ocidentais-reais\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&quot;De-risking&quot; deveria ter como alvo riscos ocidentais reais - Xinhua - Diario de Pernambuco\" \/>\n<meta property=\"og:description\" content=\"O mundo n\u00e3o precisa do &#8220;de-risking&#8221; que visa a China, mas sim reduzir urgentemente os riscos que visam uma mentalidade com base em ideologia, confronto em bloco, exclusividade e hegemonia, riscos reais do Ocidente. Alguns pol\u00edticos ocidentais deveriam deixar o...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/diariodepe.com.br\/xinhua\/2023\/06\/12\/de-risking-deveria-ter-como-alvo-riscos-ocidentais-reais\/\" \/>\n<meta property=\"og:site_name\" content=\"Xinhua - Diario de Pernambuco\" \/>\n<meta property=\"article:published_time\" content=\"2023-06-12T16:47:14+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-12T16:47:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/diariodepe.com.br\/xinhua\/wp-content\/uploads\/sites\/3\/2023\/06\/2023061268e55884caff4b9ab98bc5afb2a34a0d_202306126f60ef74d3fd4d7ea00e76e76f621a20.png\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"589\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Diogo Gomes\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Diogo Gomes\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/diariodepe.com.br\\\/xinhua\\\/2023\\\/06\\\/12\\\/de-risking-deveria-ter-como-alvo-riscos-ocidentais-reais\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diariodepe.com.br\\\/xinhua\\\/2023\\\/06\\\/12\\\/de-risking-deveria-ter-como-alvo-riscos-ocidentais-reais\\\/\"},\"author\":{\"name\":\"Diogo Gomes\",\"@id\":\"https:\\\/\\\/diariodepe.com.br\\\/xinhua\\\/#\\\/schema\\\/person\\\/8ae74930358ae71aa2519bc1c642eeb3\"},\"headline\":\"&#8220;De-risking&#8221; deveria ter como alvo riscos ocidentais reais\",\"datePublished\":\"2023-06-12T16:47:14+00:00\",\"dateModified\":\"2023-06-12T16:47:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/diariodepe.com.br\\\/xinhua\\\/2023\\\/06\\\/12\\\/de-risking-deveria-ter-como-alvo-riscos-ocidentais-reais\\\/\"},\"wordCount\":1036,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/diariodepe.com.br\\\/xinhua\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/diariodepe.com.br\\\/xinhua\\\/2023\\\/06\\\/12\\\/de-risking-deveria-ter-como-alvo-riscos-ocidentais-reais\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/diariodepe.com.br\\\/xinhua\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2023\\\/06\\\/2023061268e55884caff4b9ab98bc5afb2a34a0d_202306126f60ef74d3fd4d7ea00e76e76f621a20.png\",\"articleSection\":[\"Internacional\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/diariodepe.com.br\\\/xinhua\\\/2023\\\/06\\\/12\\\/de-risking-deveria-ter-como-alvo-riscos-ocidentais-reais\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/diariodepe.com.br\\\/xinhua\\\/2023\\\/06\\\/12\\\/de-risking-deveria-ter-como-alvo-riscos-ocidentais-reais\\\/\",\"url\":\"https:\\\/\\\/diariodepe.com.br\\\/xinhua\\\/2023\\\/06\\\/12\\\/de-risking-deveria-ter-como-alvo-riscos-ocidentais-reais\\\/\",\"name\":\"\\\"De-risking\\\" deveria ter como alvo riscos ocidentais reais - Xinhua - Diario de Pernambuco\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diariodepe.com.br\\\/xinhua\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/diariodepe.com.br\\\/xinhua\\\/2023\\\/06\\\/12\\\/de-risking-deveria-ter-como-alvo-riscos-ocidentais-reais\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/diariodepe.com.br\\\/xinhua\\\/2023\\\/06\\\/12\\\/de-risking-deveria-ter-como-alvo-riscos-ocidentais-reais\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/diariodepe.com.br\\\/xinhua\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2023\\\/06\\\/2023061268e55884caff4b9ab98bc5afb2a34a0d_202306126f60ef74d3fd4d7ea00e76e76f621a20.png\",\"datePublished\":\"2023-06-12T16:47:14+00:00\",\"dateModified\":\"2023-06-12T16:47:17+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/diariodepe.com.br\\\/xinhua\\\/2023\\\/06\\\/12\\\/de-risking-deveria-ter-como-alvo-riscos-ocidentais-reais\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/diariodepe.com.br\\\/xinhua\\\/2023\\\/06\\\/12\\\/de-risking-deveria-ter-como-alvo-riscos-ocidentais-reais\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/diariodepe.com.br\\\/xinhua\\\/2023\\\/06\\\/12\\\/de-risking-deveria-ter-como-alvo-riscos-ocidentais-reais\\\/#primaryimage\",\"url\":\"https:\\\/\\\/diariodepe.com.br\\\/xinhua\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2023\\\/06\\\/2023061268e55884caff4b9ab98bc5afb2a34a0d_202306126f60ef74d3fd4d7ea00e76e76f621a20.png\",\"contentUrl\":\"https:\\\/\\\/diariodepe.com.br\\\/xinhua\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2023\\\/06\\\/2023061268e55884caff4b9ab98bc5afb2a34a0d_202306126f60ef74d3fd4d7ea00e76e76f621a20.png\",\"width\":900,\"height\":589,\"caption\":\"Primeira aeronave Airbus A321 \u00e9 produzida na instala\u00e7\u00e3o da Final Assembly Line Asia (FALA) em Tianjin, norte da China, no dia 9 de novembro de 2022. Foto: Zhao Zishuo\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/diariodepe.com.br\\\/xinhua\\\/2023\\\/06\\\/12\\\/de-risking-deveria-ter-como-alvo-riscos-ocidentais-reais\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/diariodepe.com.br\\\/xinhua\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"&#8220;De-risking&#8221; deveria ter como alvo riscos ocidentais reais\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/diariodepe.com.br\\\/xinhua\\\/#website\",\"url\":\"https:\\\/\\\/diariodepe.com.br\\\/xinhua\\\/\",\"name\":\"Xinhua - Diario de Pernambuco\",\"description\":\"A maior ag\u00eancia de not\u00edcias da China e um dos principais canais para conhecer o pa\u00eds\",\"publisher\":{\"@id\":\"https:\\\/\\\/diariodepe.com.br\\\/xinhua\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/diariodepe.com.br\\\/xinhua\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/diariodepe.com.br\\\/xinhua\\\/#organization\",\"name\":\"Xinhua - Diario de Pernambuco\",\"url\":\"https:\\\/\\\/diariodepe.com.br\\\/xinhua\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/diariodepe.com.br\\\/xinhua\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/diariodepe.com.br\\\/xinhua\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2020\\\/10\\\/cropped-logo-transparente-2.png\",\"contentUrl\":\"https:\\\/\\\/diariodepe.com.br\\\/xinhua\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2020\\\/10\\\/cropped-logo-transparente-2.png\",\"width\":512,\"height\":164,\"caption\":\"Xinhua - Diario de Pernambuco\"},\"image\":{\"@id\":\"https:\\\/\\\/diariodepe.com.br\\\/xinhua\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/diariodepe.com.br\\\/xinhua\\\/#\\\/schema\\\/person\\\/8ae74930358ae71aa2519bc1c642eeb3\",\"name\":\"Diogo Gomes\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a3af7f049e3dac3e14730fe7a9321495cd33b345df9166d1f792e63cd8aa31ce?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a3af7f049e3dac3e14730fe7a9321495cd33b345df9166d1f792e63cd8aa31ce?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a3af7f049e3dac3e14730fe7a9321495cd33b345df9166d1f792e63cd8aa31ce?s=96&d=mm&r=g\",\"caption\":\"Diogo Gomes\"},\"sameAs\":[\"https:\\\/\\\/www.diariodepernambuco.com.br\\\/\"],\"url\":\"https:\\\/\\\/diariodepe.com.br\\\/xinhua\\\/author\\\/diogo-gomes\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\"De-risking\" deveria ter como alvo riscos ocidentais reais - Xinhua - Diario de Pernambuco","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/diariodepe.com.br\/xinhua\/2023\/06\/12\/de-risking-deveria-ter-como-alvo-riscos-ocidentais-reais\/","og_locale":"pt_BR","og_type":"article","og_title":"\"De-risking\" deveria ter como alvo riscos ocidentais reais - Xinhua - Diario de Pernambuco","og_description":"O mundo n\u00e3o precisa do &#8220;de-risking&#8221; que visa a China, mas sim reduzir urgentemente os riscos que visam uma mentalidade com base em ideologia, confronto em bloco, exclusividade e hegemonia, riscos reais do Ocidente. Alguns pol\u00edticos ocidentais deveriam deixar o...","og_url":"https:\/\/diariodepe.com.br\/xinhua\/2023\/06\/12\/de-risking-deveria-ter-como-alvo-riscos-ocidentais-reais\/","og_site_name":"Xinhua - Diario de Pernambuco","article_published_time":"2023-06-12T16:47:14+00:00","article_modified_time":"2023-06-12T16:47:17+00:00","og_image":[{"width":900,"height":589,"url":"https:\/\/diariodepe.com.br\/xinhua\/wp-content\/uploads\/sites\/3\/2023\/06\/2023061268e55884caff4b9ab98bc5afb2a34a0d_202306126f60ef74d3fd4d7ea00e76e76f621a20.png","type":"image\/png"}],"author":"Diogo Gomes","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Diogo Gomes","Est. tempo de leitura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/diariodepe.com.br\/xinhua\/2023\/06\/12\/de-risking-deveria-ter-como-alvo-riscos-ocidentais-reais\/#article","isPartOf":{"@id":"https:\/\/diariodepe.com.br\/xinhua\/2023\/06\/12\/de-risking-deveria-ter-como-alvo-riscos-ocidentais-reais\/"},"author":{"name":"Diogo Gomes","@id":"https:\/\/diariodepe.com.br\/xinhua\/#\/schema\/person\/8ae74930358ae71aa2519bc1c642eeb3"},"headline":"&#8220;De-risking&#8221; deveria ter como alvo riscos ocidentais reais","datePublished":"2023-06-12T16:47:14+00:00","dateModified":"2023-06-12T16:47:17+00:00","mainEntityOfPage":{"@id":"https:\/\/diariodepe.com.br\/xinhua\/2023\/06\/12\/de-risking-deveria-ter-como-alvo-riscos-ocidentais-reais\/"},"wordCount":1036,"commentCount":0,"publisher":{"@id":"https:\/\/diariodepe.com.br\/xinhua\/#organization"},"image":{"@id":"https:\/\/diariodepe.com.br\/xinhua\/2023\/06\/12\/de-risking-deveria-ter-como-alvo-riscos-ocidentais-reais\/#primaryimage"},"thumbnailUrl":"https:\/\/diariodepe.com.br\/xinhua\/wp-content\/uploads\/sites\/3\/2023\/06\/2023061268e55884caff4b9ab98bc5afb2a34a0d_202306126f60ef74d3fd4d7ea00e76e76f621a20.png","articleSection":["Internacional"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/diariodepe.com.br\/xinhua\/2023\/06\/12\/de-risking-deveria-ter-como-alvo-riscos-ocidentais-reais\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/diariodepe.com.br\/xinhua\/2023\/06\/12\/de-risking-deveria-ter-como-alvo-riscos-ocidentais-reais\/","url":"https:\/\/diariodepe.com.br\/xinhua\/2023\/06\/12\/de-risking-deveria-ter-como-alvo-riscos-ocidentais-reais\/","name":"\"De-risking\" deveria ter como alvo riscos ocidentais reais - Xinhua - Diario de Pernambuco","isPartOf":{"@id":"https:\/\/diariodepe.com.br\/xinhua\/#website"},"primaryImageOfPage":{"@id":"https:\/\/diariodepe.com.br\/xinhua\/2023\/06\/12\/de-risking-deveria-ter-como-alvo-riscos-ocidentais-reais\/#primaryimage"},"image":{"@id":"https:\/\/diariodepe.com.br\/xinhua\/2023\/06\/12\/de-risking-deveria-ter-como-alvo-riscos-ocidentais-reais\/#primaryimage"},"thumbnailUrl":"https:\/\/diariodepe.com.br\/xinhua\/wp-content\/uploads\/sites\/3\/2023\/06\/2023061268e55884caff4b9ab98bc5afb2a34a0d_202306126f60ef74d3fd4d7ea00e76e76f621a20.png","datePublished":"2023-06-12T16:47:14+00:00","dateModified":"2023-06-12T16:47:17+00:00","breadcrumb":{"@id":"https:\/\/diariodepe.com.br\/xinhua\/2023\/06\/12\/de-risking-deveria-ter-como-alvo-riscos-ocidentais-reais\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/diariodepe.com.br\/xinhua\/2023\/06\/12\/de-risking-deveria-ter-como-alvo-riscos-ocidentais-reais\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/diariodepe.com.br\/xinhua\/2023\/06\/12\/de-risking-deveria-ter-como-alvo-riscos-ocidentais-reais\/#primaryimage","url":"https:\/\/diariodepe.com.br\/xinhua\/wp-content\/uploads\/sites\/3\/2023\/06\/2023061268e55884caff4b9ab98bc5afb2a34a0d_202306126f60ef74d3fd4d7ea00e76e76f621a20.png","contentUrl":"https:\/\/diariodepe.com.br\/xinhua\/wp-content\/uploads\/sites\/3\/2023\/06\/2023061268e55884caff4b9ab98bc5afb2a34a0d_202306126f60ef74d3fd4d7ea00e76e76f621a20.png","width":900,"height":589,"caption":"Primeira aeronave Airbus A321 \u00e9 produzida na instala\u00e7\u00e3o da Final Assembly Line Asia (FALA) em Tianjin, norte da China, no dia 9 de novembro de 2022. Foto: Zhao Zishuo"},{"@type":"BreadcrumbList","@id":"https:\/\/diariodepe.com.br\/xinhua\/2023\/06\/12\/de-risking-deveria-ter-como-alvo-riscos-ocidentais-reais\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/diariodepe.com.br\/xinhua\/"},{"@type":"ListItem","position":2,"name":"&#8220;De-risking&#8221; deveria ter como alvo riscos ocidentais reais"}]},{"@type":"WebSite","@id":"https:\/\/diariodepe.com.br\/xinhua\/#website","url":"https:\/\/diariodepe.com.br\/xinhua\/","name":"Xinhua - Diario de Pernambuco","description":"A maior ag\u00eancia de not\u00edcias da China e um dos principais canais para conhecer o pa\u00eds","publisher":{"@id":"https:\/\/diariodepe.com.br\/xinhua\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/diariodepe.com.br\/xinhua\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/diariodepe.com.br\/xinhua\/#organization","name":"Xinhua - Diario de Pernambuco","url":"https:\/\/diariodepe.com.br\/xinhua\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/diariodepe.com.br\/xinhua\/#\/schema\/logo\/image\/","url":"https:\/\/diariodepe.com.br\/xinhua\/wp-content\/uploads\/sites\/3\/2020\/10\/cropped-logo-transparente-2.png","contentUrl":"https:\/\/diariodepe.com.br\/xinhua\/wp-content\/uploads\/sites\/3\/2020\/10\/cropped-logo-transparente-2.png","width":512,"height":164,"caption":"Xinhua - Diario de Pernambuco"},"image":{"@id":"https:\/\/diariodepe.com.br\/xinhua\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/diariodepe.com.br\/xinhua\/#\/schema\/person\/8ae74930358ae71aa2519bc1c642eeb3","name":"Diogo Gomes","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/a3af7f049e3dac3e14730fe7a9321495cd33b345df9166d1f792e63cd8aa31ce?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a3af7f049e3dac3e14730fe7a9321495cd33b345df9166d1f792e63cd8aa31ce?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a3af7f049e3dac3e14730fe7a9321495cd33b345df9166d1f792e63cd8aa31ce?s=96&d=mm&r=g","caption":"Diogo Gomes"},"sameAs":["https:\/\/www.diariodepernambuco.com.br\/"],"url":"https:\/\/diariodepe.com.br\/xinhua\/author\/diogo-gomes\/"}]}},"cc_featured_image_caption":{"caption_text":"","source_text":"","source_url":""},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/diariodepe.com.br\/xinhua\/wp-json\/wp\/v2\/posts\/13514","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diariodepe.com.br\/xinhua\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diariodepe.com.br\/xinhua\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diariodepe.com.br\/xinhua\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/diariodepe.com.br\/xinhua\/wp-json\/wp\/v2\/comments?post=13514"}],"version-history":[{"count":1,"href":"https:\/\/diariodepe.com.br\/xinhua\/wp-json\/wp\/v2\/posts\/13514\/revisions"}],"predecessor-version":[{"id":13517,"href":"https:\/\/diariodepe.com.br\/xinhua\/wp-json\/wp\/v2\/posts\/13514\/revisions\/13517"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diariodepe.com.br\/xinhua\/wp-json\/wp\/v2\/media\/13515"}],"wp:attachment":[{"href":"https:\/\/diariodepe.com.br\/xinhua\/wp-json\/wp\/v2\/media?parent=13514"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diariodepe.com.br\/xinhua\/wp-json\/wp\/v2\/categories?post=13514"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diariodepe.com.br\/xinhua\/wp-json\/wp\/v2\/tags?post=13514"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}