{"id":12408,"date":"2023-05-04T11:17:56","date_gmt":"2023-05-04T14:17:56","guid":{"rendered":"https:\/\/www.diariodepe.com.br\/xinhua\/?p=12408"},"modified":"2023-05-09T19:32:01","modified_gmt":"2023-05-09T22:32:01","slug":"transmissao-ao-vivo-da-impulso-para-fabricas-chinesas-exportarem","status":"publish","type":"post","link":"https:\/\/diariodepe.com.br\/xinhua\/2023\/05\/04\/transmissao-ao-vivo-da-impulso-para-fabricas-chinesas-exportarem\/","title":{"rendered":"Transmiss\u00e3o ao vivo d\u00e1 impulso para f\u00e1bricas chinesas exportarem"},"content":{"rendered":"\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<p>Hangzhou \u2014 Os exportadores chineses encontraram uma nova maneira de aumentar as vendas instalando salas de transmiss\u00e3o ao vivo (livestreaming) dentro de suas f\u00e1bricas, promovendo diretamente uma ampla variedade de produtos, desde roupas, escavadeiras at\u00e9 totens de carregamento el\u00e9trico para compradores globais.<\/p>\n\n\n\n<p>&nbsp; &nbsp;Todas as ter\u00e7as e quintas-feiras, a Yiwu O-Choice Import and Export, fornecedora l\u00edder de sedas e fronhas, lan\u00e7a sess\u00f5es de transmiss\u00e3o no Alibaba.com, um mercado online business-to-business para atacadistas de todo o mundo.<\/p>\n\n\n\n<p>&nbsp; &nbsp;Entre os mais de 60 funcion\u00e1rios da equipe de com\u00e9rcio exterior da empresa, mais de 10 se transformaram em livestreamers. Durante uma sess\u00e3o recente de uma hora, as vendas de seus produtos de seda atingiram US$ 650 mil, de acordo com o gerente geral Liu Mingyang.<\/p>\n\n\n\n<p>&nbsp; &nbsp;\u201cCome\u00e7amos a transmitir ao vivo no ano passado e isso se tornou parte de nosso trabalho di\u00e1rio\u201d, destacou Liu, acrescentando que a transmiss\u00e3o ao vivo transfronteiri\u00e7a e v\u00eddeos curtos melhoraram muito a efici\u00eancia de suas transa\u00e7\u00f5es.<\/p>\n\n\n\n<p>&nbsp; &nbsp;A Yiwu O-Choice est\u00e1 entre uma s\u00e9rie de empresas chinesas voltadas para a exporta\u00e7\u00e3o que est\u00e3o surfando uma nova onda de com\u00e9rcio eletr\u00f4nico transfronteiri\u00e7o para chegar a compradores estrangeiros e impulsionar sua recupera\u00e7\u00e3o comercial.<\/p>\n\n\n\n<p>&nbsp; &nbsp;A fabricante chinesa de roupas esportivas Zhejiang Aidu Garments decidiu mergulhar de cabe\u00e7a no marketing de transmiss\u00e3o ao vivo no segundo semestre de 2021. No primeiro trimestre deste ano, a empresa registrou um aumento de 38% nas vendas ano a ano.<\/p>\n\n\n\n<p>&nbsp; &nbsp;\u201cAo levar compradores do exterior para uma visita virtual ao nosso escrit\u00f3rio, centro de pesquisa e desenvolvimento e sala de exposi\u00e7\u00f5es, conseguimos pedidos de forma mais r\u00e1pida e eficiente\u201d, revelou Lai Guorong, gerente geral da Aidu.<\/p>\n\n\n\n<p>&nbsp; &nbsp;A virada das empresas para o livestreaming est\u00e1 sendo acelerada pelos esfor\u00e7os do Alibaba.com.<\/p>\n\n\n\n<p>&nbsp; &nbsp;Desde que lan\u00e7ou o servi\u00e7o de transmiss\u00e3o ao vivo transfronteiri\u00e7a, h\u00e1 dois anos, mais de 40 mil empresas experimentaram a nova abordagem, com uma m\u00e9dia de 5 mil a 6 mil sess\u00f5es de transmiss\u00e3o realizadas por dia, de acordo com Zhang Kuo, presidente do Alibaba.com.<\/p>\n\n\n\n<p>&nbsp; &nbsp;Os dados mostraram que, de janeiro a mar\u00e7o, o n\u00famero de espectadores do exterior que assistiram \u00e0 transmiss\u00e3o ao vivo no Alibaba.com aumentou 198% ano a ano.<\/p>\n\n\n\n<p>&nbsp;Economistas acreditam que o com\u00e9rcio eletr\u00f4nico por transmiss\u00e3o ao vivo impulsionou a recupera\u00e7\u00e3o do com\u00e9rcio na China durante seu empenho de digitaliza\u00e7\u00e3o.<\/p>\n\n\n\n<p>&nbsp; &nbsp;O com\u00e9rcio exterior da China teve um in\u00edcio est\u00e1vel em 2023, com as importa\u00e7\u00f5es e exporta\u00e7\u00f5es totais de bens se expandindo 4,8% em termos anuais no primeiro trimestre, revertendo uma queda de 0,8% nos primeiros dois meses do ano, mostraram dados oficiais.<\/p>\n\n\n\n<p>&nbsp; &nbsp;Nos primeiros tr\u00eas meses, as exporta\u00e7\u00f5es cresceram 8,4% ano a ano, para 5,65 trilh\u00f5es de yuans (US$ 816 bilh\u00f5es), enquanto as importa\u00e7\u00f5es aumentaram 0,2%, para 4,24 trilh\u00f5es de yuans, elevando o com\u00e9rcio total para 9,89 trilh\u00f5es de yuans.<\/p>\n\n\n\n<p>&nbsp; &nbsp;De acordo com uma reuni\u00e3o do Conselho de Estado realizada no in\u00edcio de abril, a China far\u00e1 mais esfor\u00e7os para implementar uma combina\u00e7\u00e3o de pol\u00edticas para manter a estabilidade do com\u00e9rcio exterior e ajudar as empresas a conseguirem encomendas e expandirem o mercado.<\/p>\n\n\n\n<p>&nbsp; &nbsp;\u201cA transmiss\u00e3o ao vivo transfronteiri\u00e7a pode ajudar compradores e vendedores a estabelecerem confian\u00e7a rapidamente. A nova abordagem ter\u00e1 um enorme potencial no futuro\u201d, disse Liu.<\/p>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Hangzhou \u2014 Os exportadores chineses encontraram uma nova maneira de aumentar as vendas instalando salas de transmiss\u00e3o ao vivo (livestreaming) dentro de suas f\u00e1bricas, promovendo diretamente uma ampla variedade de produtos, desde roupas, escavadeiras at\u00e9 totens de carregamento el\u00e9trico para&#8230;<\/p>\n","protected":false},"author":6,"featured_media":12410,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-12408","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-china"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Transmiss\u00e3o ao vivo d\u00e1 impulso para f\u00e1bricas chinesas exportarem - Xinhua - Diario de Pernambuco<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/diariodepe.com.br\/xinhua\/2023\/05\/04\/transmissao-ao-vivo-da-impulso-para-fabricas-chinesas-exportarem\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Transmiss\u00e3o ao vivo d\u00e1 impulso para f\u00e1bricas chinesas exportarem - Xinhua - Diario de Pernambuco\" \/>\n<meta property=\"og:description\" content=\"Hangzhou \u2014 Os exportadores chineses encontraram uma nova maneira de aumentar as vendas instalando salas de transmiss\u00e3o ao vivo (livestreaming) dentro de suas f\u00e1bricas, promovendo diretamente uma ampla variedade de produtos, desde roupas, escavadeiras at\u00e9 totens de carregamento el\u00e9trico para...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/diariodepe.com.br\/xinhua\/2023\/05\/04\/transmissao-ao-vivo-da-impulso-para-fabricas-chinesas-exportarem\/\" \/>\n<meta property=\"og:site_name\" content=\"Xinhua - Diario de Pernambuco\" \/>\n<meta property=\"article:published_time\" content=\"2023-05-04T14:17:56+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-05-09T22:32:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/diariodepe.com.br\/xinhua\/wp-content\/uploads\/sites\/3\/2023\/05\/202305022dd54322083842838ff5c4222394ac2d_63192243-0d40-433f-aefe-dc1ae05d0df9-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Diogo Gomes\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Diogo Gomes\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/diariodepe.com.br\\\/xinhua\\\/2023\\\/05\\\/04\\\/transmissao-ao-vivo-da-impulso-para-fabricas-chinesas-exportarem\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diariodepe.com.br\\\/xinhua\\\/2023\\\/05\\\/04\\\/transmissao-ao-vivo-da-impulso-para-fabricas-chinesas-exportarem\\\/\"},\"author\":{\"name\":\"Diogo Gomes\",\"@id\":\"https:\\\/\\\/diariodepe.com.br\\\/xinhua\\\/#\\\/schema\\\/person\\\/8ae74930358ae71aa2519bc1c642eeb3\"},\"headline\":\"Transmiss\u00e3o ao vivo d\u00e1 impulso para f\u00e1bricas chinesas exportarem\",\"datePublished\":\"2023-05-04T14:17:56+00:00\",\"dateModified\":\"2023-05-09T22:32:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/diariodepe.com.br\\\/xinhua\\\/2023\\\/05\\\/04\\\/transmissao-ao-vivo-da-impulso-para-fabricas-chinesas-exportarem\\\/\"},\"wordCount\":615,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/diariodepe.com.br\\\/xinhua\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/diariodepe.com.br\\\/xinhua\\\/2023\\\/05\\\/04\\\/transmissao-ao-vivo-da-impulso-para-fabricas-chinesas-exportarem\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/diariodepe.com.br\\\/xinhua\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2023\\\/05\\\/202305022dd54322083842838ff5c4222394ac2d_63192243-0d40-433f-aefe-dc1ae05d0df9-1.jpg\",\"articleSection\":[\"China\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/diariodepe.com.br\\\/xinhua\\\/2023\\\/05\\\/04\\\/transmissao-ao-vivo-da-impulso-para-fabricas-chinesas-exportarem\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/diariodepe.com.br\\\/xinhua\\\/2023\\\/05\\\/04\\\/transmissao-ao-vivo-da-impulso-para-fabricas-chinesas-exportarem\\\/\",\"url\":\"https:\\\/\\\/diariodepe.com.br\\\/xinhua\\\/2023\\\/05\\\/04\\\/transmissao-ao-vivo-da-impulso-para-fabricas-chinesas-exportarem\\\/\",\"name\":\"Transmiss\u00e3o ao vivo d\u00e1 impulso para f\u00e1bricas chinesas exportarem - Xinhua - Diario de Pernambuco\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diariodepe.com.br\\\/xinhua\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/diariodepe.com.br\\\/xinhua\\\/2023\\\/05\\\/04\\\/transmissao-ao-vivo-da-impulso-para-fabricas-chinesas-exportarem\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/diariodepe.com.br\\\/xinhua\\\/2023\\\/05\\\/04\\\/transmissao-ao-vivo-da-impulso-para-fabricas-chinesas-exportarem\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/diariodepe.com.br\\\/xinhua\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2023\\\/05\\\/202305022dd54322083842838ff5c4222394ac2d_63192243-0d40-433f-aefe-dc1ae05d0df9-1.jpg\",\"datePublished\":\"2023-05-04T14:17:56+00:00\",\"dateModified\":\"2023-05-09T22:32:01+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/diariodepe.com.br\\\/xinhua\\\/2023\\\/05\\\/04\\\/transmissao-ao-vivo-da-impulso-para-fabricas-chinesas-exportarem\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/diariodepe.com.br\\\/xinhua\\\/2023\\\/05\\\/04\\\/transmissao-ao-vivo-da-impulso-para-fabricas-chinesas-exportarem\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/diariodepe.com.br\\\/xinhua\\\/2023\\\/05\\\/04\\\/transmissao-ao-vivo-da-impulso-para-fabricas-chinesas-exportarem\\\/#primaryimage\",\"url\":\"https:\\\/\\\/diariodepe.com.br\\\/xinhua\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2023\\\/05\\\/202305022dd54322083842838ff5c4222394ac2d_63192243-0d40-433f-aefe-dc1ae05d0df9-1.jpg\",\"contentUrl\":\"https:\\\/\\\/diariodepe.com.br\\\/xinhua\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2023\\\/05\\\/202305022dd54322083842838ff5c4222394ac2d_63192243-0d40-433f-aefe-dc1ae05d0df9-1.jpg\",\"width\":900,\"height\":600,\"caption\":\"Foto: Lin Shanchuan\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/diariodepe.com.br\\\/xinhua\\\/2023\\\/05\\\/04\\\/transmissao-ao-vivo-da-impulso-para-fabricas-chinesas-exportarem\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/diariodepe.com.br\\\/xinhua\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Transmiss\u00e3o ao vivo d\u00e1 impulso para f\u00e1bricas chinesas exportarem\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/diariodepe.com.br\\\/xinhua\\\/#website\",\"url\":\"https:\\\/\\\/diariodepe.com.br\\\/xinhua\\\/\",\"name\":\"Xinhua - Diario de Pernambuco\",\"description\":\"A maior ag\u00eancia de not\u00edcias da China e um dos principais canais para conhecer o pa\u00eds\",\"publisher\":{\"@id\":\"https:\\\/\\\/diariodepe.com.br\\\/xinhua\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/diariodepe.com.br\\\/xinhua\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/diariodepe.com.br\\\/xinhua\\\/#organization\",\"name\":\"Xinhua - Diario de Pernambuco\",\"url\":\"https:\\\/\\\/diariodepe.com.br\\\/xinhua\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/diariodepe.com.br\\\/xinhua\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/diariodepe.com.br\\\/xinhua\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2020\\\/10\\\/cropped-logo-transparente-2.png\",\"contentUrl\":\"https:\\\/\\\/diariodepe.com.br\\\/xinhua\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2020\\\/10\\\/cropped-logo-transparente-2.png\",\"width\":512,\"height\":164,\"caption\":\"Xinhua - Diario de Pernambuco\"},\"image\":{\"@id\":\"https:\\\/\\\/diariodepe.com.br\\\/xinhua\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/diariodepe.com.br\\\/xinhua\\\/#\\\/schema\\\/person\\\/8ae74930358ae71aa2519bc1c642eeb3\",\"name\":\"Diogo Gomes\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a3af7f049e3dac3e14730fe7a9321495cd33b345df9166d1f792e63cd8aa31ce?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a3af7f049e3dac3e14730fe7a9321495cd33b345df9166d1f792e63cd8aa31ce?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a3af7f049e3dac3e14730fe7a9321495cd33b345df9166d1f792e63cd8aa31ce?s=96&d=mm&r=g\",\"caption\":\"Diogo Gomes\"},\"sameAs\":[\"https:\\\/\\\/www.diariodepernambuco.com.br\\\/\"],\"url\":\"https:\\\/\\\/diariodepe.com.br\\\/xinhua\\\/author\\\/diogo-gomes\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Transmiss\u00e3o ao vivo d\u00e1 impulso para f\u00e1bricas chinesas exportarem - Xinhua - Diario de Pernambuco","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/diariodepe.com.br\/xinhua\/2023\/05\/04\/transmissao-ao-vivo-da-impulso-para-fabricas-chinesas-exportarem\/","og_locale":"pt_BR","og_type":"article","og_title":"Transmiss\u00e3o ao vivo d\u00e1 impulso para f\u00e1bricas chinesas exportarem - Xinhua - Diario de Pernambuco","og_description":"Hangzhou \u2014 Os exportadores chineses encontraram uma nova maneira de aumentar as vendas instalando salas de transmiss\u00e3o ao vivo (livestreaming) dentro de suas f\u00e1bricas, promovendo diretamente uma ampla variedade de produtos, desde roupas, escavadeiras at\u00e9 totens de carregamento el\u00e9trico para...","og_url":"https:\/\/diariodepe.com.br\/xinhua\/2023\/05\/04\/transmissao-ao-vivo-da-impulso-para-fabricas-chinesas-exportarem\/","og_site_name":"Xinhua - Diario de Pernambuco","article_published_time":"2023-05-04T14:17:56+00:00","article_modified_time":"2023-05-09T22:32:01+00:00","og_image":[{"width":900,"height":600,"url":"https:\/\/diariodepe.com.br\/xinhua\/wp-content\/uploads\/sites\/3\/2023\/05\/202305022dd54322083842838ff5c4222394ac2d_63192243-0d40-433f-aefe-dc1ae05d0df9-1.jpg","type":"image\/jpeg"}],"author":"Diogo Gomes","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Diogo Gomes","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/diariodepe.com.br\/xinhua\/2023\/05\/04\/transmissao-ao-vivo-da-impulso-para-fabricas-chinesas-exportarem\/#article","isPartOf":{"@id":"https:\/\/diariodepe.com.br\/xinhua\/2023\/05\/04\/transmissao-ao-vivo-da-impulso-para-fabricas-chinesas-exportarem\/"},"author":{"name":"Diogo Gomes","@id":"https:\/\/diariodepe.com.br\/xinhua\/#\/schema\/person\/8ae74930358ae71aa2519bc1c642eeb3"},"headline":"Transmiss\u00e3o ao vivo d\u00e1 impulso para f\u00e1bricas chinesas exportarem","datePublished":"2023-05-04T14:17:56+00:00","dateModified":"2023-05-09T22:32:01+00:00","mainEntityOfPage":{"@id":"https:\/\/diariodepe.com.br\/xinhua\/2023\/05\/04\/transmissao-ao-vivo-da-impulso-para-fabricas-chinesas-exportarem\/"},"wordCount":615,"commentCount":0,"publisher":{"@id":"https:\/\/diariodepe.com.br\/xinhua\/#organization"},"image":{"@id":"https:\/\/diariodepe.com.br\/xinhua\/2023\/05\/04\/transmissao-ao-vivo-da-impulso-para-fabricas-chinesas-exportarem\/#primaryimage"},"thumbnailUrl":"https:\/\/diariodepe.com.br\/xinhua\/wp-content\/uploads\/sites\/3\/2023\/05\/202305022dd54322083842838ff5c4222394ac2d_63192243-0d40-433f-aefe-dc1ae05d0df9-1.jpg","articleSection":["China"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/diariodepe.com.br\/xinhua\/2023\/05\/04\/transmissao-ao-vivo-da-impulso-para-fabricas-chinesas-exportarem\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/diariodepe.com.br\/xinhua\/2023\/05\/04\/transmissao-ao-vivo-da-impulso-para-fabricas-chinesas-exportarem\/","url":"https:\/\/diariodepe.com.br\/xinhua\/2023\/05\/04\/transmissao-ao-vivo-da-impulso-para-fabricas-chinesas-exportarem\/","name":"Transmiss\u00e3o ao vivo d\u00e1 impulso para f\u00e1bricas chinesas exportarem - Xinhua - Diario de Pernambuco","isPartOf":{"@id":"https:\/\/diariodepe.com.br\/xinhua\/#website"},"primaryImageOfPage":{"@id":"https:\/\/diariodepe.com.br\/xinhua\/2023\/05\/04\/transmissao-ao-vivo-da-impulso-para-fabricas-chinesas-exportarem\/#primaryimage"},"image":{"@id":"https:\/\/diariodepe.com.br\/xinhua\/2023\/05\/04\/transmissao-ao-vivo-da-impulso-para-fabricas-chinesas-exportarem\/#primaryimage"},"thumbnailUrl":"https:\/\/diariodepe.com.br\/xinhua\/wp-content\/uploads\/sites\/3\/2023\/05\/202305022dd54322083842838ff5c4222394ac2d_63192243-0d40-433f-aefe-dc1ae05d0df9-1.jpg","datePublished":"2023-05-04T14:17:56+00:00","dateModified":"2023-05-09T22:32:01+00:00","breadcrumb":{"@id":"https:\/\/diariodepe.com.br\/xinhua\/2023\/05\/04\/transmissao-ao-vivo-da-impulso-para-fabricas-chinesas-exportarem\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/diariodepe.com.br\/xinhua\/2023\/05\/04\/transmissao-ao-vivo-da-impulso-para-fabricas-chinesas-exportarem\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/diariodepe.com.br\/xinhua\/2023\/05\/04\/transmissao-ao-vivo-da-impulso-para-fabricas-chinesas-exportarem\/#primaryimage","url":"https:\/\/diariodepe.com.br\/xinhua\/wp-content\/uploads\/sites\/3\/2023\/05\/202305022dd54322083842838ff5c4222394ac2d_63192243-0d40-433f-aefe-dc1ae05d0df9-1.jpg","contentUrl":"https:\/\/diariodepe.com.br\/xinhua\/wp-content\/uploads\/sites\/3\/2023\/05\/202305022dd54322083842838ff5c4222394ac2d_63192243-0d40-433f-aefe-dc1ae05d0df9-1.jpg","width":900,"height":600,"caption":"Foto: Lin Shanchuan"},{"@type":"BreadcrumbList","@id":"https:\/\/diariodepe.com.br\/xinhua\/2023\/05\/04\/transmissao-ao-vivo-da-impulso-para-fabricas-chinesas-exportarem\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/diariodepe.com.br\/xinhua\/"},{"@type":"ListItem","position":2,"name":"Transmiss\u00e3o ao vivo d\u00e1 impulso para f\u00e1bricas chinesas exportarem"}]},{"@type":"WebSite","@id":"https:\/\/diariodepe.com.br\/xinhua\/#website","url":"https:\/\/diariodepe.com.br\/xinhua\/","name":"Xinhua - Diario de Pernambuco","description":"A maior ag\u00eancia de not\u00edcias da China e um dos principais canais para conhecer o pa\u00eds","publisher":{"@id":"https:\/\/diariodepe.com.br\/xinhua\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/diariodepe.com.br\/xinhua\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/diariodepe.com.br\/xinhua\/#organization","name":"Xinhua - Diario de Pernambuco","url":"https:\/\/diariodepe.com.br\/xinhua\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/diariodepe.com.br\/xinhua\/#\/schema\/logo\/image\/","url":"https:\/\/diariodepe.com.br\/xinhua\/wp-content\/uploads\/sites\/3\/2020\/10\/cropped-logo-transparente-2.png","contentUrl":"https:\/\/diariodepe.com.br\/xinhua\/wp-content\/uploads\/sites\/3\/2020\/10\/cropped-logo-transparente-2.png","width":512,"height":164,"caption":"Xinhua - Diario de Pernambuco"},"image":{"@id":"https:\/\/diariodepe.com.br\/xinhua\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/diariodepe.com.br\/xinhua\/#\/schema\/person\/8ae74930358ae71aa2519bc1c642eeb3","name":"Diogo Gomes","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/a3af7f049e3dac3e14730fe7a9321495cd33b345df9166d1f792e63cd8aa31ce?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a3af7f049e3dac3e14730fe7a9321495cd33b345df9166d1f792e63cd8aa31ce?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a3af7f049e3dac3e14730fe7a9321495cd33b345df9166d1f792e63cd8aa31ce?s=96&d=mm&r=g","caption":"Diogo Gomes"},"sameAs":["https:\/\/www.diariodepernambuco.com.br\/"],"url":"https:\/\/diariodepe.com.br\/xinhua\/author\/diogo-gomes\/"}]}},"cc_featured_image_caption":{"caption_text":"","source_text":"","source_url":""},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/diariodepe.com.br\/xinhua\/wp-json\/wp\/v2\/posts\/12408","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diariodepe.com.br\/xinhua\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diariodepe.com.br\/xinhua\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diariodepe.com.br\/xinhua\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/diariodepe.com.br\/xinhua\/wp-json\/wp\/v2\/comments?post=12408"}],"version-history":[{"count":3,"href":"https:\/\/diariodepe.com.br\/xinhua\/wp-json\/wp\/v2\/posts\/12408\/revisions"}],"predecessor-version":[{"id":12573,"href":"https:\/\/diariodepe.com.br\/xinhua\/wp-json\/wp\/v2\/posts\/12408\/revisions\/12573"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diariodepe.com.br\/xinhua\/wp-json\/wp\/v2\/media\/12410"}],"wp:attachment":[{"href":"https:\/\/diariodepe.com.br\/xinhua\/wp-json\/wp\/v2\/media?parent=12408"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diariodepe.com.br\/xinhua\/wp-json\/wp\/v2\/categories?post=12408"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diariodepe.com.br\/xinhua\/wp-json\/wp\/v2\/tags?post=12408"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}